{"id":3075,"count":2,"description":"","link":"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/","name":"Exerzierplatz","slug":"exerzierplatz-en","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3075\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/tag\\\/exerzierplatz-en\\\/#listItem\",\"name\":\"Exerzierplatz\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/tag\\\/exerzierplatz-en\\\/#listItem\",\"position\":2,\"name\":\"Exerzierplatz\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3075\\\/#collectionpage\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3075\\\/\",\"name\":\"Exerzierplatz | We love Kiel\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/3075\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#organization\",\"name\":\"We love Kiel\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeLoveKielCity\\\/\",\"https:\\\/\\\/www.instagram.com\\\/welovekiel\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/\",\"name\":\"We love Kiel\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Exerzierplatz | We love Kiel","description":"","canonical_url":"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags\/3075\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/welovekiel.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/#listItem","name":"Exerzierplatz"}},{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/#listItem","position":2,"name":"Exerzierplatz","previousItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/en\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags\/3075\/#collectionpage","url":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags\/3075\/","name":"Exerzierplatz | We love Kiel","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/welovekiel.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags\/3075\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/welovekiel.com\/en\/#organization","name":"We love Kiel","url":"https:\/\/welovekiel.com\/en\/","sameAs":["https:\/\/www.facebook.com\/WeLoveKielCity\/","https:\/\/www.instagram.com\/welovekiel\/"]},{"@type":"WebSite","@id":"https:\/\/welovekiel.com\/en\/#website","url":"https:\/\/welovekiel.com\/en\/","name":"We love Kiel","inLanguage":"en-US","publisher":{"@id":"https:\/\/welovekiel.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/welovekiel.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tExerzierplatz\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/welovekiel.com\/en\/"},{"label":"Exerzierplatz","link":"https:\/\/welovekiel.com\/en\/tag\/exerzierplatz-en\/"}],"_links":{"self":[{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags\/3075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/posts?tags=3075"},{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tribe_events?tags=3075"},{"href":"https:\/\/welovekiel.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=3075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}