{"id":12516,"date":"2022-12-22T02:16:11","date_gmt":"2022-12-22T01:16:11","guid":{"rendered":"https:\/\/welovekiel.com\/?post_type=tribe_events&#038;p=12516"},"modified":"2022-12-22T02:16:11","modified_gmt":"2022-12-22T01:16:11","slug":"flohmarkt-schoenberg-fussgaengerzone-21-05-2023","status":"publish","type":"tribe_events","link":"https:\/\/welovekiel.com\/de\/event\/flohmarkt-schoenberg-fussgaengerzone-21-05-2023\/","title":{"rendered":"Flohmarkt Sch\u00f6nberg Fu\u00dfg\u00e4ngerzone 21.05.2023"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\"><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p><strong>Flohmarkt Sch&ouml;nberg Fu&szlig;g&auml;ngerzone am Sonntag, den 21. Mai 2023 ab 8 Uhr in der Sch&ouml;nberger Fu&szlig;g&auml;ngerzone in der Kn&uuml;ll.<\/strong><\/p>\n<p>In den Monaten M&auml;rz bis Oktober 2023 veranstaltet Olaf Platner Veranstaltungs- und Eventmanagement insgesamt sechs Flohm&auml;rkte im Ostseebad Sch&ouml;nberg in der Fu&szlig;g&auml;ngerzone in der Kn&uuml;ll. Auf dem Flohmarkt in Sch&ouml;nberg stehen keine &uuml;berdachten Flohmarktst&auml;nde zur Verf&uuml;gung. Hier auf dem Sch&ouml;nberger Flohmarkt l&auml;sst sich sicher das eine oder andere Schn&auml;ppchen in der Fu&szlig;g&auml;ngerzone finden.<\/p>\n<p><strong>Der Flohmarkt in Sch&ouml;nberg findet in 2023 an folgenden Sonntagen von 8 bis 16 Uhr statt:<\/strong><\/p>\n<ul>\n<li>Sonntag, 12. M&auml;rz 2023<\/li>\n<li>Sonntag, 16. April 2023<\/li>\n<li><strong>Sonntag, 21. Mai 2023<\/strong><\/li>\n<li>Sonntag, 25. Juni 2023<\/li>\n<li>Sonntag, 13. August 2023<\/li>\n<li>Dienstag, 03. Oktober 2023<\/li>\n<\/ul>\n<p>Es wird kein Eintritt f&uuml;r Besucher der Flohm&auml;rkte in Gettorf erhoben. F&uuml;r Verk&auml;ufer betr&auml;gt die Standgeb&uuml;hr pauschal 7,- Euro je angefangenen laufenden Meter f&uuml;r einen Stand ohne Auto sowie 8,- Euro je Meter mit Auto, Mindestabnahme 5 Meter. Bei Transportern betr&auml;gt die Mindestabnahme 6 Meter. Anh&auml;nger gelten als Auto. Fahrzeuge beziehungsweise Anh&auml;nger m&uuml;ssen vorab gebucht werden. Aufbau ab 6.00 Uhr.<\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\" style=\"margin-top:0px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Flohmarkt Sch&ouml;nberg Fu&szlig;g&auml;ngerzone<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-gallery-1 .fusion-gallery-image {border:0px solid #f6f6f6;}<\/style><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;\"><div class=\"fusion-gallery fusion-gallery-container fusion-grid-1 fusion-columns-total-3 fusion-gallery-layout-grid fusion-gallery-1\" style=\"margin:-5px;\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-1 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland.jpg\" data-title=\"Flohmarkt Kiel Mettenhof Kaufland\" title=\"Flohmarkt Kiel Mettenhof Kaufland\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland.jpg\" width=\"1200\" height=\"900\" alt=\"Flohmarkt Kiel Mettenhof Kaufland\" title=\"Flohmarkt Kiel Mettenhof Kaufland\" aria-label=\"Flohmarkt Kiel Mettenhof Kaufland\" class=\"lazyload img-responsive wp-image-9733\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-mettenhof-kaufland.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 640px) 1100px, \"><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-1 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten.jpg\" data-title=\"Flohmarkt Stand Antiquit&auml;ten\" title=\"Flohmarkt Stand Antiquit&auml;ten\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten.jpg\" width=\"1200\" height=\"900\" alt=\"Flohmarkt Stand Antiquit&auml;ten\" title=\"Flohmarkt Stand Antiquit&auml;ten\" aria-label=\"Flohmarkt Stand Antiquit&auml;ten\" class=\"lazyload img-responsive wp-image-9597\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-antiquitaeten.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 640px) 1100px, \"><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-1 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug.jpg\" data-title=\"Flohmarkt Kiel Holzspielzeug\" title=\"Flohmarkt Kiel Holzspielzeug\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug.jpg\" width=\"1200\" height=\"900\" alt=\"Flohmarkt Kiel Holzspielzeug\" title=\"Flohmarkt Kiel Holzspielzeug\" aria-label=\"Flohmarkt Kiel Holzspielzeug\" class=\"lazyload img-responsive wp-image-8585\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-holzspielzeug.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 640px) 1100px, \"><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-2{margin-top:15px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-2{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-two\" style=\"margin-top:15px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Mehr &uuml;ber Flohmarkt und M&auml;rkte in Kiel &amp; Umgebung<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-2\"><ul class=\"posts-by-tag-list\"><li class=\"posts-by-tag-item Flohmarkt Flohmarkt Kiel H&ouml;rn H&ouml;rn Campus H&ouml;rn-Areal Innenstadt Kieler H&ouml;rn\" id=\"posts-by-tag-item-9416\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/erster-flohmarkt-des-jahres-an-der-kieler-hoern-9416\/\">Erster Flohmarkt des Jahres an der Kieler H&ouml;rn<\/a> <small>Posted on: 24. April 2022<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Europaplatz Fleeth&ouml;rn Flohmarkt Holstenstra&szlig;e Innenstadt Kieler Innenstadt Rathausplatz\" id=\"posts-by-tag-item-8683\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/erster-flohmarkt-in-der-kieler-innenstadt-in-2022-8683\/\">Erster Flohmarkt in der Kieler Innenstadt in 2022<\/a> <small>Posted on: 3. April 2022<\/small><\/li><\/ul>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-3{margin-top:20px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-3{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-two\" style=\"margin-top:20px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Videos Flohm&auml;rkte in Kiel<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 1\" src=\"https:\/\/www.youtube.com\/embed\/fJHk-WSYXK0?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-section-separator section-separator slant fusion-section-separator-1\"><div class=\"fusion-section-separator-svg\" style=\"padding:0;\"><svg class=\"fusion-slant-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" height=\"100\" viewbox=\"0 0 100 100\" preserveaspectratio=\"none\" style=\"padding:0;\" fill=\"rgba(246,246,246,1)\"><path d=\"M100 0 L100 100 L0 0 Z\"><\/path><\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\" style=\"height:99px;\"><\/div><\/div><style type=\"text\/css\">.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:2.56%;margin-right:2.56%;}@media only screen and (max-width:1024px) {.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:1.92%;margin-right:1.92%;}}@media only screen and (max-width:640px) {.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:1.92%;margin-right:1.92%;}}.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg svg,.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg-bg{height:5px;}.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-spacer-height{height:5px !important;padding-top:inherit !important;}<\/style><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 2\" src=\"https:\/\/www.youtube.com\/embed\/5vI6XlPa0JI?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:75% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.56%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.56%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-widget-area fusion-widget-area-1 fusion-content-widget-area\"><style type=\"text\/css\">.fusion-widget-area-1 {padding:0px 0px 0px 0px;}.fusion-widget-area-1 .widget h4 {color:#333333;}.fusion-widget-area-1 .widget .heading h4 {color:#333333;}<\/style><div class=\"tribe-compatibility-container\">\n\t<div class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" data-js=\"tribe-events-view\" data-view-rest-url=\"https:\/\/welovekiel.com\/de\/wp-json\/tribe\/views\/v2\/html\" data-view-manage-url=\"1\" data-view-breakpoint-pointer=\"95621c0f-4c97-432d-b8f8-6f890f4bb2a3\">\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kaufland Schwentinental \/ Raisdorf am Donnerstag, den 14. Mai 2026 ab 8.00 Uhr auf dem Kaufland Parkplatz in der Mergenthalerstra\\u00dfe (ehemals real). Am 14.05.2026 veranstaltet Hochberg Flohm\\u00e4rkte einen gro\\u00dfen Flohmarkt auf dem Kaufland Parkplatz [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-verkaufsstand-figuren-sammeln.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-14T08:00:00+02:00\",\"endDate\":\"2026-05-14T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Kaufland Schwentinental\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/kaufland-schwentinental\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Mergenthalerstra\\u00dfe 13-21\",\"addressLocality\":\"Schwentinental\",\"postalCode\":\"24223\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Wik 17.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Wik am Sonntag, den 17. Mai 2026 ab 6 Uhr auf dem famila Parkplatz im Kieler Stadtteil Wik in der Prinz-Heinrich-Stra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/famila-flohmarkt-kiel-wik.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-17T06:00:00+02:00\",\"endDate\":\"2026-05-17T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Wik\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-wik\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Prinz-Heinrich-Stra\\u00dfe 20\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24106\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Citti-Park Kiel 17.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt Citti-Park Kiel am Sonntag, den 17. Mai 2026 ab 8 Uhr auf dem Citti-Park Parkplatz im M\\u00fchlendamm 1 im Kieler Stadtteil Hassee. An insgesamt sechs Terminen im Jahr 2026 veranstaltet die Firma Hochberg Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-citti-park.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-17T08:00:00+02:00\",\"endDate\":\"2026-05-17T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Citti-Park Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/citti-park-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"M\\u00fchlendamm 1\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24113\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Gettorf Fu\\u00dfg\\u00e4ngerzone 31.05.2026\",\"description\":\"&lt;p&gt;Flohmarkt Gettorf Fu\\u00dfg\\u00e4ngerzone am Sonntag, den 31. Mai 2026 ab 8 Uhr in der Gettorfer Fu\\u00dfg\\u00e4ngerzone in der Teichstra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Olaf Platner Veranstaltungs- und Eventmanagement insgesamt acht Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-deko-glaeser.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-31-05-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-31T08:00:00+02:00\",\"endDate\":\"2026-05-31T15:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Gettorf Fu\\u00dfg\\u00e4ngerzone\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/gettorf-fussgaengerzone\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Teichstra\\u00dfe\",\"addressLocality\":\"Gettorf\",\"postalCode\":\"24214\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Olaf Platner Veranstaltungs- und Eventmanagement\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-31-05-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-04-25T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Neumeimersdorf 31.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Neumeimersdorf am Sonntag, den 31. Mai 2026 ab 8.30 Uhr auf dem famila Parkplatz im Kieler Stadtteil Meimersdorf in der Grot-Steenbusch. Am 31.05.2026 veranstaltet Hochberg Flohm\\u00e4rkte den beliebten Flohmarkt bei famila in Neumeimersdorf. [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-famila-kiel-neu-mielkendorf.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-31-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-31T08:30:00+02:00\",\"endDate\":\"2026-05-31T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Neumeimersdorf\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-neumeimersdorf\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Grot Steenbusch 35\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24145\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-31-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 07.06.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kiel Innenstadt am Sonntag, den 7. Juni 2026 ab 8 Uhr auf dem Rathausplatz, Asmus-Bremer-Platz, Europaplatz, Fleeth\\u00f6rn, Willestra\\u00dfe, Holstenplatz und Holstenstra\\u00dfe. In den Monaten April bis September 2026 veranstaltet die Landeshauptstadt Kiel mehrere Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/kieler-rathausplatz-flohmarkt-innenstadt-kiel.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-7-6-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-07T08:00:00+02:00\",\"endDate\":\"2026-06-07T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Rathausplatz Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/rathausplatz-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rathausplatz\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24103\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Landeshauptstadt Kiel\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-7-6-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kaufland Kiel-Mettenhof 14.06.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kaufland Kiel-Mettenhof am Sonntag, den 14. Juni 2026 ab 6 Uhr auf dem Kaufland Parkplatz im Kieler Stadtteil Mettenhof am Skandinaviendamm. In den Monaten Januar bis Dezember 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt 12 [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/kaufland-mettenhof-parkhaus-flohmarkt.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-14-06-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-14T06:00:00+02:00\",\"endDate\":\"2026-06-14T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Kaufland Kiel-Mettenhof\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/kaufland-kiel-mettenhof\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Skandinaviendamm 299\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24109\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-14-06-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Preetz Innenstadt 14.06.2026\",\"description\":\"&lt;p&gt;Flohmarkt Preetz Innenstadt am Sonntag, den 14. Juni 2026 ab 7.00 Uhr in der Preetzer Innenstadt zentral gelegen auf dem Marktplatz in Preetz. In den Monaten Mai bis Oktober 2026 finden mehrere Flohm\\u00e4rkte in der [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-schmuck.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-14-6-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-14T07:00:00+02:00\",\"endDate\":\"2026-06-14T17:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Marktplatz Preetz\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/marktplatz-preetz\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Marktplatz\",\"addressLocality\":\"Preetz\",\"postalCode\":\"24211\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-14-6-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-04-26T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Citti-Park Kiel 14.6.2026\",\"description\":\"&lt;p&gt;Flohmarkt Citti-Park Kiel am Sonntag, den 14. Juni 2026 ab 8 Uhr auf dem Citti-Park Parkplatz im M\\u00fchlendamm 1 im Kieler Stadtteil Hassee. An insgesamt sechs Terminen im Jahr 2026 veranstaltet die Firma Hochberg Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-citti-park.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-14-6-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-14T08:00:00+02:00\",\"endDate\":\"2026-06-14T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Citti-Park Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/citti-park-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"M\\u00fchlendamm 1\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24113\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-14-6-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Wik 21.6.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Wik am Sonntag, den 21. Juni 2026 ab 6 Uhr auf dem famila Parkplatz im Kieler Stadtteil Wik in der Prinz-Heinrich-Stra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/famila-flohmarkt-kiel-wik.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-21-6-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-06-21T06:00:00+02:00\",\"endDate\":\"2026-06-21T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Wik\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-wik\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Prinz-Heinrich-Stra\\u00dfe 20\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24106\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-21-6-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&paged=2\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Veranstaltungen von 13. Mai \\u2013 21. Juni \\u2013 We love Kiel\",\"limit\":\"10\",\"no_upcoming_events\":false,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Titel:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-title\",\"name\":\"widget-tribe-widget-events-list[2][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Anzeige:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-limit\",\"name\":\"widget-tribe-widget-events-list[2][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Anzeige:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Preis\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-cost\",\"name\":\"widget-tribe-widget-events-list[2][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Veranstaltungsort\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-venue\",\"name\":\"widget-tribe-widget-events-list[2][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Stra\\u00dfe\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-street\",\"name\":\"widget-tribe-widget-events-list[2][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"Stadt\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-city\",\"name\":\"widget-tribe-widget-events-list[2][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"Staat (USA) oder Bundesland \\\/ Kanton (International)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-region\",\"name\":\"widget-tribe-widget-events-list[2][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Postleitzahl\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-zip\",\"name\":\"widget-tribe-widget-events-list[2][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Land\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-country\",\"name\":\"widget-tribe-widget-events-list[2][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Telefon\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-phone\",\"name\":\"widget-tribe-widget-events-list[2][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Veranstalter\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-organizer\",\"name\":\"widget-tribe-widget-events-list[2][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Webseite\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-website\",\"name\":\"widget-tribe-widget-events-list[2][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-metadata_section\",\"name\":\"widget-tribe-widget-events-list[2][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filter:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[2][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[2][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Filter zuf\\u00fcgen:\",\"placeholder\":\"W\\u00e4hle einen Taxonomiebegriff\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-taxonomy\",\"name\":\"widget-tribe-widget-events-list[2][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Blende dieses Widget aus, wenn es keine bevorstehenden Veranstaltungen gibt.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[2][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Nur auf hervorgehobene Veranstaltungen beschr\\u00e4nken\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[2][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"JSON-LD-Daten generieren\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[2][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":false,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":\"\",\"wpml_language\":\"de\",\"fusion_display_title\":\"yes\",\"fusion_padding_color\":\"\",\"fusion_margin\":\"\",\"fusion_bg_color\":\"\",\"fusion_bg_radius_size\":\"\",\"fusion_border_size\":\"\",\"fusion_border_style\":\"solid\",\"fusion_border_color\":\"\",\"fusion_divider_color\":\"\",\"fusion_align\":\"\",\"fusion_align_mobile\":\"\",\"events\":[10000655,10000638,10000646,10000665,10000607,10000631,10000622,10000672,10000647,10000639],\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-13 00:00:00\",\"now\":\"2026-05-13 03:27:08\",\"home_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"rest_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Ftribe_events%2F12516\",\"today_title\":\"Klicke, um das heutige Datum auszuw\\u00e4hlen\",\"today_label\":\"Heute\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d.m.Y\",\"month_and_year_compact\":\"m.Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" | \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Veranstaltungen als iCal exportieren\",\"title\":\"Diese Funktion verwenden, um Kalenderdaten mit Google Kalender, Apple iCal und kompatiblen Apps zu teilen\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"95621c0f-4c97-432d-b8f8-6f890f4bb2a3\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Liste\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Zeige Veranstaltungen in der Liste Ansicht\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Monat\\\/\",\"view_label\":\"Monat\",\"aria_label\":\"Zeige Veranstaltungen in der Monat Ansicht\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/heute\\\/\",\"view_label\":\"Tag\",\"aria_label\":\"Zeige Veranstaltungen in der Tag Ansicht\"},\"week\":{\"view_class\":\"Tribe\\\\Events\\\\Pro\\\\Views\\\\V2\\\\Views\\\\Week_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Woche\\\/\",\"view_label\":\"Woche\",\"aria_label\":\"Zeige Veranstaltungen in der Woche Ansicht\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Kalender anzeigen\",\"view_more_title\":\"Weitere Veranstaltungen anzeigen.\",\"view_more_link\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/\",\"widget_title\":\"Anstehende Veranstaltungen\",\"hide_if_no_upcoming_events\":false,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Kalender\",\"single_label\":\"Zu Google Kalender hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Zu iCalendar hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\".ics-Datei exportieren\",\"single_label\":\".ics-Datei exportieren\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exportiere Outlook .ics Datei\",\"single_label\":\"Exportiere Outlook .ics Datei\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tAnstehende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000655 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kaufland tag-flohmarkt-kaufland-raisdorf tag-flohmarkt-kaufland-schwentinental tag-flohmarkt-kiel tag-flohmarkt-raisdorf tag-flohmarkt-schwentinental tag-kaufland tag-kaufland-flohmarkt tag-kaufland-raisdorf tag-kaufland-schwentinental tag-kiel tag-mergenthalerstrasse tag-raisdorf tag-schwentinental tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-kieler-umland tribe_events_cat-meimersdorf tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-14\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\" title=\"Flohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000638 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-wik tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-wik tag-flohmarkt-kiel tag-kiel tag-prinz-heinrich-strasse tag-shopping tag-wik tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping tribe_events_cat-wik gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\" title=\"Flohmarkt famila Kiel-Wik 17.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Wik 17.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000646 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-citti-park tag-citti-park-flohmarkt tag-citti-park-kiel tag-flohmarkt tag-flohmarkt-kiel tag-hassee tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-hassee tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\" title=\"Flohmarkt Citti-Park Kiel 17.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Citti-Park Kiel 17.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-31\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t31\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000665 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-gettorf tag-fussgaengerzone tag-gettorf tag-kieler-umland tag-kreis-rendsburg-eckernfoerde tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kieler-umland tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-31\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">15:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-31-05-2026\/\" title=\"Flohmarkt Gettorf Fu&szlig;g&auml;ngerzone 31.05.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Gettorf Fu&szlig;g&auml;ngerzone 31.05.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-31\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t31\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000607 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-neumeimersdorf tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-neumeimersdorf tag-flohmarkt-kiel tag-grot-steenbusch tag-kiel tag-meimersdorf tag-neumeimersdorf tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-meimersdorf tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-31\">\n\t\t<span class=\"tribe-event-date-start\">08:30<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-31-5-2026\/\" title=\"Flohmarkt famila Kiel-Neumeimersdorf 31.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Neumeimersdorf 31.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-07\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t7\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000631 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-asmus-bremer-platz tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-kieler-innenstadt tag-flohmarkt-rathausplatz tag-holstenplatz tag-holstenstrasse tag-rathausplatz tag-willestrasse tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-07\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-7-6-2026\/\" title=\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 07.06.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 07.06.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000622 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-mettenhof tag-kaufland tag-kaufland-flohmarkt tag-kaufland-mettenhof tag-kiel tag-mettenhof tag-mettenhof-fohmarkt tag-shopping tag-skandinaviendamm tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-mettenhof tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-14-06-2026\/\" title=\"Flohmarkt Kaufland Kiel-Mettenhof 14.06.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kaufland Kiel-Mettenhof 14.06.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000672 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kieler-umland tag-flohmarkt-preetz tag-kreis-ploen tag-marktplatz tag-marktplatz-preetz tag-preetz tag-preetz-innenstadt tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kieler-umland tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-event-date-start\">07:00<\/span> - <span class=\"tribe-event-time\">17:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-14-6-2026\/\" title=\"Flohmarkt Preetz Innenstadt 14.06.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Preetz Innenstadt 14.06.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000647 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-citti-park tag-citti-park-flohmarkt tag-citti-park-kiel tag-flohmarkt tag-flohmarkt-kiel tag-hassee tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-hassee tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-14\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-14-6-2026\/\" title=\"Flohmarkt Citti-Park Kiel 14.6.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Citti-Park Kiel 14.6.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-06-21\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tJuni\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t21\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000639 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-wik tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-wik tag-flohmarkt-kiel tag-kiel tag-prinz-heinrich-strasse tag-shopping tag-wik tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping tribe_events_cat-wik gallery-content-unit cat_flohmarkt cat_kieler-umland cat_shopping\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-06-21\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-21-6-2026\/\" title=\"Flohmarkt famila Kiel-Wik 21.6.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Wik 21.6.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/Veranstaltungen\/\" class=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\" title=\"Weitere Veranstaltungen anzeigen.\">\n\t\tKalender anzeigen\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js=\"tribe-events-view-nonce-data\" type=\"application\/json\">{\"tvn1\":\"db914eb4b1\",\"tvn2\":\"\"}<\/script><div id=\"custom_html-13\" class=\"widget_text widget widget_custom_html\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"textwidget custom-html-widget\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- welovekiel_de_blog_sidebar_responsive -->\r\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-2675294892226297\" data-ad-slot=\"8830049817\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div><\/div>\n\t\t<div id=\"recent-posts-6\" class=\"widget widget_recent_entries\" style=\"border-style: solid;border-color:transparent;border-width:0px;\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Neu im Kiel-Blog<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/buehnenaufbau-holstein-kiel-aufstiegsparty-rathausplatz-16867\/\">B&uuml;hnenaufbau Holstein Kiel Aufstiegsparty Rathausplatz Sonntagnachmittag<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/holstein-kiel-bundesliga-fans-holstein-stadion-16835\/\">Holstein Kiel Bundesliga Aufstiegsparty am Holstein-Stadion nach Unentschieden gegen D&uuml;sseldorf<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/div><div id=\"encyclopedia_items-8\" class=\"widget widget_encyclopedia_items\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"heading\"><h4 class=\"widget-title\">Aus dem Kiel-Lexikon<\/h4><\/div><ul>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/kiel-schilksee\/\" title=\"\" class=\"encyclopedia\">Schilksee<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/schilksee-strand\/\" title=\"\" class=\"encyclopedia\">Schilksee Strand<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/wind-licht-objekt\/\" title=\"\" class=\"encyclopedia\">Wind-Licht-Objekt<\/a><\/li>\n    <\/ul>\n<\/div><div class=\"fusion-additional-widget-content\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:25% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 7.68%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 7.68%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":8563,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[1191,2402,2390,102,2403,2388,2389,438],"tribe_events_cat":[1310,784,987],"class_list":["post-12516","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-flohmarkt","tag-flohmarkt-schoenberg","tag-fussgaengerzone","tag-kieler-umland","tag-kreis-ploen","tag-schoenberg","tag-schoenberger-strand","tag-shopping","tribe_events_cat-flohmarkt","tribe_events_cat-kieler-umland","tribe_events_cat-shopping","gallery-content-unit"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events\/12516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events\/12516\/revisions"}],"predecessor-version":[{"id":12521,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events\/12516\/revisions\/12521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media\/8563"}],"wp:attachment":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media?parent=12516"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tags?post=12516"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=12516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}