{"id":11695,"date":"2022-11-08T19:42:53","date_gmt":"2022-11-08T18:42:53","guid":{"rendered":"https:\/\/welovekiel.com\/?post_type=tribe_events&#038;p=11695"},"modified":"2022-11-09T08:57:54","modified_gmt":"2022-11-09T07:57:54","slug":"historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022","status":"publish","type":"tribe_events","link":"https:\/\/welovekiel.com\/de\/event\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\/","title":{"rendered":"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\"><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p><strong><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/historischer-weihnachtsmarkt-gut-bossee\/\" target=\"_self\" title=\"\" class=\"encyclopedia\">Historischer Weihnachtsmarkt Gut Bossee<\/a> 3. Adventssamstag 2022 am Samstag, den 10. Dezember 2022 &ndash; Der Weihnachtsmarkt auf Gut Bossee z&auml;hlt zu einem der sch&ouml;nsten Weihnachtsm&auml;rkte im Kieler Umland.<\/strong><\/p>\n<p>Gut Bossee liegt rund 25 Kilometer von Kiel entfernt. Zwischen Kiel und Rendsburg gelegen und nicht weit vom Bossee und Westensee entfernt, ist der Historische Weihnachtsmarkt gut mit dem Auto &uuml;ber die A 210 zu erreichen.<\/p>\n<p>Ge&ouml;ffnet hat der Weihnachtsmarkt auf Gut Bossee jeweils nur an den beiden letzten Adventswochenenden. Dementsprechend gut besucht ist der Weihnachtsmarkt dann an den vier Tagen im Dezember 2022. Da die Parkpl&auml;tze begrenzt sind empfiehlt sich eine m&ouml;glichst fr&uuml;he Anreise mit dem Auto. Wer direkt um 11 Uhr ankommt, der sollte ohne gr&ouml;&szlig;ere Wartezeiten einen der rund 400 Parkpl&auml;tze bekommen und kann dann ganz entspannt die Zeit auf dem Historischen Weihnachtsmarkt genie&szlig;en.<\/p>\n<p>In der gro&szlig;en Scheune bieten zahlreiche Aussteller ihre Waren an, darunter regionale Spezialit&auml;ten, Handgemachtes, Geschenkideen und vieles mehr. Sehr lecker ist auch der Punsch, hergestellt nach altem Familienrezept. Nat&uuml;rlich gibt es auch alkoholfreien Punsch sowie andere hei&szlig;e und kalte Getr&auml;nke.<\/p>\n<h2>Historischer Weihnachtsmarkt am 3. und 4. Adventswochenende auf Gut Bossee<\/h2>\n<ul>\n<li>abwechslungsreiches Rahmenprogramm f&uuml;r Klein und Gro&szlig;<\/li>\n<li>Kunsthandwerk und regionale Delikatessen<\/li>\n<li>Weihnachtsb&auml;ume zum selber schlagen<\/li>\n<li>Punsch nach altem Familienrezept<\/li>\n<li>K&ouml;stliches vom Wild wie Wildbratwurst und Wildschweinleberk&auml;se<\/li>\n<\/ul>\n<h2>An welchen Tagen findet der Historische Weihnachtsmarkt in 2022 statt?<\/h2>\n<p>Der Historische Weihnachtsmarkt Gut Bossee 2022 findet an folgenden vier Tagen statt:<\/p>\n<ul>\n<li>Samstag, 10. Dezember 2022<\/li>\n<li>Sonntag, 11. Dezember 2022<\/li>\n<li>Samstag, 17. Dezember 2022<\/li>\n<li>Sonntag, 18. Dezember 2022<\/li>\n<\/ul>\n<h2>Parkplatz &amp; Eintritt<\/h2>\n<p>Der Eintritt zum Historischen Weihnachtsmarkt ist frei. Bei Anreise mit dem Auto: Parkplatz 2,- Euro<\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\" style=\"margin-top:0px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Bilder Historischer Weihnachtsmarkt Bossee<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-gallery-1 .fusion-gallery-image {border:0px solid #f6f6f6;}<\/style><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;\"><div class=\"fusion-gallery fusion-gallery-container fusion-grid-2 fusion-columns-total-4 fusion-gallery-layout-grid fusion-gallery-1\" style=\"margin:-5px;\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-2 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee.jpg\" data-title=\"Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee.jpg\" width=\"1200\" height=\"900\" alt=\"Historischer Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" aria-label=\"Weihnachtsmarkt Gut Bossee\" class=\"lazyload img-responsive wp-image-1538\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-gut-bossee.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 548px, (min-width: 640px) 712px, \"><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-2 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune.jpg\" data-title=\"Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune.jpg\" width=\"1200\" height=\"900\" alt=\"Historischer Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" aria-label=\"Weihnachtsmarkt Gut Bossee\" class=\"lazyload img-responsive wp-image-1536\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/weihnachtsmarkt-bossee-scheune.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 548px, (min-width: 640px) 712px, \"><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-2 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018.jpg\" data-title=\"Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018.jpg\" width=\"1200\" height=\"900\" alt=\"Scheune Weihnachtsmarkt Gut Bossee\" title=\"Weihnachtsmarkt Gut Bossee\" aria-label=\"Weihnachtsmarkt Gut Bossee\" class=\"lazyload img-responsive wp-image-1534\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/gut-bossee-weihnachtsmarkt-2018.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 548px, (min-width: 640px) 712px, \"><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-2 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt.jpg\" data-title=\"Historischer Weihnachtsmarkt Gut Bossee\" title=\"Historischer Weihnachtsmarkt Gut Bossee\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt.jpg\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt.jpg\" width=\"1200\" height=\"900\" alt=\"Historischer Weihnachtsmarkt Gut Bossee\" title=\"Historischer Weihnachtsmarkt Gut Bossee\" aria-label=\"Historischer Weihnachtsmarkt Gut Bossee\" class=\"lazyload img-responsive wp-image-1530\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/bossee-gutshof-weihnachtsmarkt.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 548px, (min-width: 640px) 712px, \"><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-2{margin-top:20px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-2{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-two\" style=\"margin-top:20px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Weihnachtszeit in Kiel und Umgebung<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-2\"><ul class=\"posts-by-tag-list\"><li class=\"posts-by-tag-item Beleuchtung Deutsche Marine Gorch Fock Marineschiffe Marinest&uuml;tzpunkt Kiel-Wik Segelschulschiff Weihnachten Weihnachtszeit\" id=\"posts-by-tag-item-12574\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/segelschulschiff-gorch-fock-weihnachtsbeleuchtung-marinestuetzpunkt-12574\/\">Segelschulschiff Gorch Fock mit Weihnachtsbeleuchtung im Kieler Marinest&uuml;tzpunkt<\/a> <small>Posted on: 23. Dezember 2022<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Bernhardt-Minetti-Platz Gl&uuml;hwein Holstenplatz Kieler Weihnachtsdorf Kieler Weihnachtsm&auml;rkte Rathausplatz Shopping Weihnachtsmarkt Weihnachtsmarkt 2022 Weihnachtszeit\" id=\"posts-by-tag-item-11999\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/weihnachtsmarkt-kiel-2022-am-montag-eroeffnet-11999\/\">Weihnachtsmarkt Kiel 2022 am Montag er&ouml;ffnet<\/a> <small>Posted on: 22. November 2022<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Bernhardt-Minetti-Platz Gl&uuml;hwein Gut Augustenhof Gut Bossee Gut Steinwehr Historischer Weihnachtsmarkt Holstenplatz Kieler Weihnachtsdorf Kieler Weihnachtsm&auml;rkte Kilian Rathausplatz Weihnachtsmarkt Weihnachtsmarkt 2022 Weihnachtswichtel Kilian\" id=\"posts-by-tag-item-11823\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/am-21-11-2022-oeffnen-die-kieler-weihnachtsmaerkte-11823\/\">Nur noch 10 Tage: Am 21.11.2022 &ouml;ffnen die Kieler Weihnachtsm&auml;rkte<\/a> <small>Posted on: 11. November 2022<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Corona COVID-19 Holstenstra&szlig;e Holtenauer Stra&szlig;e Kieler Weihnachtsdorf Weihnachtsmarkt Weihnachtsmarkt Kiel\" id=\"posts-by-tag-item-7718\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/weihnachtsmarkt-kiel-2g-regelung-7718\/\">Weihnachtsmarkt Kiel: 2G-Regelung ab 4. Dezember 2021<\/a> <small>Posted on: 2. Dezember 2021<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Holstenplatz Holstenstra&szlig;e Holtenauer Stra&szlig;e Kieler Weihnachtsdorf Kieler Weihnachtsm&auml;rkte Rathausplatz Weihnachtsmarkt Weihnachtsmarkt Kiel Weihnachtswichtel Kilian\" id=\"posts-by-tag-item-7700\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/weihnachtsmarkt-kiel-2021-eroeffnet-7700\/\">Weihnachtsmarkt Kiel 2021 am Montag er&ouml;ffnet<\/a> <small>Posted on: 23. November 2021<\/small><\/li><li class=\"posts-by-tag-item Asmus-Bremer-Platz Bernhardt-Minetti-Platz Corona COVID-19 Holstenplatz Kieler Weihnachtsm&auml;rkte Rathausplatz Weihnachtsdorf Weihnachtsmarkt Weihnachtsmarkt 2021\" id=\"posts-by-tag-item-7531\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/weihnachtsmarkt-kiel-2021-corona-regeln-7531\/\">Welche Corona-Regeln gelten auf dem Weihnachtsmarkt Kiel 2021?<\/a> <small>Posted on: 17. November 2021<\/small><\/li><li class=\"posts-by-tag-item Corona COVID-19 Heiligabend lillebr&auml;u Weihnachten Weihnachtszeit\" id=\"posts-by-tag-item-4267\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/heiligabend-2020-in-kiel-besinnliche-weihnachten-in-kleiner-runde-4267\/\">Heiligabend 2020 in Kiel - Besinnliche Weihnachten in kleiner Runde<\/a> <small>Posted on: 25. Dezember 2020<\/small><\/li><li class=\"posts-by-tag-item COVID-19 Kieler Weihnachtsm&auml;rkte Weihnachtsdorf Weihnachtsmarkt Weihnachtszeit\" id=\"posts-by-tag-item-4186\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/abgesagt-kieler-weihnachtsmarkt-2020-4186\/\">Abgesagt: Kieler Weihnachtsmarkt 2020 findet nicht statt<\/a> <small>Posted on: 1. November 2020<\/small><\/li><\/ul>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-3{margin-top:20px!important; margin-right:0px!important;margin-bottom:31px!important;margin-left:0px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-3{margin-top:0px!important; margin-right:0px!important;margin-bottom:20px!important; margin-left:0px!important;}}<\/style><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-two\" style=\"margin-top:20px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"title-heading-left\" style=\"margin:0;\">Videos Gut Bossee Historischer Weihnachtsmarkt<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 1\" src=\"https:\/\/www.youtube.com\/embed\/ImTxZsFOZ9k?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-section-separator section-separator slant fusion-section-separator-1\"><div class=\"fusion-section-separator-svg\" style=\"padding:0;\"><svg class=\"fusion-slant-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" height=\"100\" viewbox=\"0 0 100 100\" preserveaspectratio=\"none\" style=\"padding:0;\" fill=\"rgba(246,246,246,1)\"><path d=\"M100 0 L100 100 L0 0 Z\"><\/path><\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\" style=\"height:99px;\"><\/div><\/div><style type=\"text\/css\">.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:2.56%;margin-right:2.56%;}@media only screen and (max-width:1024px) {.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:1.92%;margin-right:1.92%;}}@media only screen and (max-width:640px) {.fusion-section-separator-1 .fusion-section-separator-svg {margin-left:1.92%;margin-right:1.92%;}}.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg svg,.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg-bg{height:5px;}.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-spacer-height{height:5px !important;padding-top:inherit !important;}<\/style><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 2\" src=\"https:\/\/www.youtube.com\/embed\/Y1shEG36GDg?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:75% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.56%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.56%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-widget-area fusion-widget-area-1 fusion-content-widget-area\"><style type=\"text\/css\">.fusion-widget-area-1 {padding:0px 0px 0px 0px;}.fusion-widget-area-1 .widget h4 {color:#333333;}.fusion-widget-area-1 .widget .heading h4 {color:#333333;}<\/style><div class=\"tribe-compatibility-container\">\n\t<div class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" data-js=\"tribe-events-view\" data-view-rest-url=\"https:\/\/welovekiel.com\/de\/wp-json\/tribe\/views\/v2\/html\" data-view-manage-url=\"1\" data-view-breakpoint-pointer=\"b575d42b-a9ef-48a8-9504-0d7ecab16781\">\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 06.09.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kiel Innenstadt am Sonntag, den 6. September 2026 ab 8 Uhr auf dem Rathausplatz, Asmus-Bremer-Platz, Europaplatz, Fleeth\\u00f6rn, Willestra\\u00dfe, Holstenplatz und Holstenstra\\u00dfe. In den Monaten April bis September 2026 veranstaltet die Landeshauptstadt Kiel mehrere Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/kieler-rathausplatz-flohmarkt-innenstadt-kiel.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-6-9-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-06T08:00:00+02:00\",\"endDate\":\"2026-09-06T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Rathausplatz Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/rathausplatz-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rathausplatz\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24103\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Landeshauptstadt Kiel\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-6-9-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kaufland Kiel-Mettenhof 13.09.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kaufland Kiel-Mettenhof am Sonntag, den 13. September 2026 ab 6 Uhr auf dem Kaufland Parkplatz im Kieler Stadtteil Mettenhof am Skandinaviendamm. In den Monaten Januar bis Dezember 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt 12 [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/kaufland-mettenhof-parkhaus-flohmarkt.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-13-09-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-13T06:00:00+02:00\",\"endDate\":\"2026-09-13T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Kaufland Kiel-Mettenhof\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/kaufland-kiel-mettenhof\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Skandinaviendamm 299\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24109\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-13-09-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Citti-Park Kiel 13.9.2026\",\"description\":\"&lt;p&gt;Flohmarkt Citti-Park Kiel am Sonntag, den 13. September 2026 ab 8 Uhr auf dem Citti-Park Parkplatz im M\\u00fchlendamm 1 im Kieler Stadtteil Hassee. An insgesamt sechs Terminen im Jahr 2026 veranstaltet die Firma Hochberg Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-citti-park.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-13-9-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-13T08:00:00+02:00\",\"endDate\":\"2026-09-13T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Citti-Park Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/citti-park-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"M\\u00fchlendamm 1\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24113\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-13-9-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Wik 20.9.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Wik am Sonntag, den 20. September 2026 ab 6 Uhr auf dem famila Parkplatz im Kieler Stadtteil Wik in der Prinz-Heinrich-Stra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/famila-flohmarkt-kiel-wik.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-20-9-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-20T06:00:00+02:00\",\"endDate\":\"2026-09-20T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Wik\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-wik\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Prinz-Heinrich-Stra\\u00dfe 20\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24106\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-20-9-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Preetz Innenstadt 20.09.2026\",\"description\":\"&lt;p&gt;Flohmarkt Preetz Innenstadt am Sonntag, den 20. September 2026 ab 7.00 Uhr in der Preetzer Innenstadt zentral gelegen auf dem Marktplatz in Preetz. In den Monaten Mai bis Oktober 2026 finden mehrere Flohm\\u00e4rkte in der [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-schmuck.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-20-09-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-20T07:00:00+02:00\",\"endDate\":\"2026-09-20T17:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Marktplatz Preetz\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/marktplatz-preetz\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Marktplatz\",\"addressLocality\":\"Preetz\",\"postalCode\":\"24211\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-20-09-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-04-26T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Gettorf Fu\\u00dfg\\u00e4ngerzone 20.09.2026\",\"description\":\"&lt;p&gt;Flohmarkt Gettorf Fu\\u00dfg\\u00e4ngerzone am Sonntag, den 20. September 2026 ab 8 Uhr in der Gettorfer Fu\\u00dfg\\u00e4ngerzone in der Teichstra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Olaf Platner Veranstaltungs- und Eventmanagement insgesamt acht Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-deko-glaeser.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-20-09-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-20T08:00:00+02:00\",\"endDate\":\"2026-09-20T15:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Gettorf Fu\\u00dfg\\u00e4ngerzone\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/gettorf-fussgaengerzone\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Teichstra\\u00dfe\",\"addressLocality\":\"Gettorf\",\"postalCode\":\"24214\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Olaf Platner Veranstaltungs- und Eventmanagement\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-20-09-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-04-25T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 27.09.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kiel Innenstadt am Sonntag, den 27. September 2026 ab 8 Uhr auf dem Rathausplatz, Asmus-Bremer-Platz, Europaplatz, Fleeth\\u00f6rn, Willestra\\u00dfe, Holstenplatz und Holstenstra\\u00dfe. In den Monaten April bis September 2026 veranstaltet die Landeshauptstadt Kiel mehrere Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/kieler-rathausplatz-flohmarkt-innenstadt-kiel.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-27-9-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-27T08:00:00+02:00\",\"endDate\":\"2026-09-27T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Rathausplatz Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/rathausplatz-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rathausplatz\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24103\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Landeshauptstadt Kiel\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-27-9-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Neumeimersdorf 27.9.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Neumeimersdorf am Sonntag, den 27. September 2026 ab 8.30 Uhr auf dem famila Parkplatz im Kieler Stadtteil Meimersdorf in der Grot-Steenbusch. Am 27.09.2026 veranstaltet Hochberg Flohm\\u00e4rkte den beliebten Flohmarkt bei famila in Neumeimersdorf. [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-famila-kiel-neu-mielkendorf.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-27-9-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-09-27T08:30:00+02:00\",\"endDate\":\"2026-09-27T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Neumeimersdorf\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-neumeimersdorf\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Grot Steenbusch 35\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24145\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-27-9-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Preetz Innenstadt 03.10.2026\",\"description\":\"&lt;p&gt;Flohmarkt Preetz Innenstadt am Samstag, den 3. Oktober 2026 ab 7.00 Uhr in der Preetzer Innenstadt zentral gelegen auf dem Marktplatz in Preetz. In den Monaten Mai bis Oktober 2026 finden mehrere Flohm\\u00e4rkte in der [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-schmuck.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-03-10-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-10-03T07:00:00+02:00\",\"endDate\":\"2026-10-03T17:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Marktplatz Preetz\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/marktplatz-preetz\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Marktplatz\",\"addressLocality\":\"Preetz\",\"postalCode\":\"24211\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-03-10-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"2026-04-26T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt REWE Center Kiel (Winterbeker Weg) 3.10.2026\",\"description\":\"&lt;p&gt;Flohmarkt REWE Center Kiel am Samstag, den 3. Oktober 2026 ab 8.00 Uhr auf dem REWE Parkplatz im Winterbeker Weg 44 im Kieler Stadtteil Hassee. Am 03.10.2026 veranstaltet Hochberg Flohm\\u00e4rkte den beliebten Flohmarkt bei REWE [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-stand-schmuck.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-rewe-center-kiel-winterbeker-weg-3-10-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-10-03T08:00:00+02:00\",\"endDate\":\"2026-10-03T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"REWE Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/rewe-kiel-winterbeker-weg\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Winterbeker Weg 44\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24114\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-rewe-center-kiel-winterbeker-weg-3-10-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&paged=2\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Veranstaltungen von 2. September \\u2013 3. Oktober \\u2013 We love Kiel\",\"limit\":\"10\",\"no_upcoming_events\":false,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Titel:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-title\",\"name\":\"widget-tribe-widget-events-list[2][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Anzeige:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-limit\",\"name\":\"widget-tribe-widget-events-list[2][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Anzeige:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Preis\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-cost\",\"name\":\"widget-tribe-widget-events-list[2][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Veranstaltungsort\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-venue\",\"name\":\"widget-tribe-widget-events-list[2][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Stra\\u00dfe\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-street\",\"name\":\"widget-tribe-widget-events-list[2][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"Stadt\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-city\",\"name\":\"widget-tribe-widget-events-list[2][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"Staat (USA) oder Bundesland \\\/ Kanton (International)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-region\",\"name\":\"widget-tribe-widget-events-list[2][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Postleitzahl\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-zip\",\"name\":\"widget-tribe-widget-events-list[2][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Land\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-country\",\"name\":\"widget-tribe-widget-events-list[2][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Telefon\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-phone\",\"name\":\"widget-tribe-widget-events-list[2][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Veranstalter\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-organizer\",\"name\":\"widget-tribe-widget-events-list[2][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Webseite\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-website\",\"name\":\"widget-tribe-widget-events-list[2][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-metadata_section\",\"name\":\"widget-tribe-widget-events-list[2][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filter:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[2][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-operand\",\"name\":\"widget-tribe-widget-events-list[2][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[2][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Filter zuf\\u00fcgen:\",\"placeholder\":\"W\\u00e4hle einen Taxonomiebegriff\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-taxonomy\",\"name\":\"widget-tribe-widget-events-list[2][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Blende dieses Widget aus, wenn es keine bevorstehenden Veranstaltungen gibt.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[2][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Nur auf hervorgehobene Veranstaltungen beschr\\u00e4nken\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[2][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"JSON-LD-Daten generieren\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-2-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[2][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":false,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":\"\",\"wpml_language\":\"de\",\"fusion_display_title\":\"yes\",\"fusion_padding_color\":\"\",\"fusion_margin\":\"\",\"fusion_bg_color\":\"\",\"fusion_bg_radius_size\":\"\",\"fusion_border_size\":\"\",\"fusion_border_style\":\"solid\",\"fusion_border_color\":\"\",\"fusion_divider_color\":\"\",\"fusion_align\":\"\",\"fusion_align_mobile\":\"\",\"events\":[10000634,10000625,10000648,10000642,10000674,10000669,10000635,10000610,10000675,10000654],\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-09-02 00:00:00\",\"now\":\"2026-09-02 23:41:13\",\"home_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"rest_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Ftribe_events%2F11695\",\"today_title\":\"Klicke, um das heutige Datum auszuw\\u00e4hlen\",\"today_label\":\"Heute\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d.m.Y\",\"month_and_year_compact\":\"m.Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" | \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"show_content_title\":false,\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Veranstaltungen als iCal exportieren\",\"title\":\"Diese Funktion verwenden, um Kalenderdaten mit Google Kalender, Apple iCal und kompatiblen Apps zu teilen\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"b575d42b-a9ef-48a8-9504-0d7ecab16781\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Liste\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Zeige Veranstaltungen in der Liste Ansicht\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Monat\\\/\",\"view_label\":\"Monat\",\"aria_label\":\"Zeige Veranstaltungen in der Monat Ansicht\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/heute\\\/\",\"view_label\":\"Tag\",\"aria_label\":\"Zeige Veranstaltungen in der Tag Ansicht\"},\"week\":{\"view_class\":\"Tribe\\\\Events\\\\Pro\\\\Views\\\\V2\\\\Views\\\\Week_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Woche\\\/\",\"view_label\":\"Woche\",\"aria_label\":\"Zeige Veranstaltungen in der Woche Ansicht\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Kalender anzeigen\",\"view_more_title\":\"Weitere Veranstaltungen anzeigen.\",\"view_more_link\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/\",\"widget_title\":\"Anstehende Veranstaltungen\",\"hide_if_no_upcoming_events\":false,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Kalender\",\"single_label\":\"Zu Google Kalender hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Zu iCalendar hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\".ics-Datei exportieren\",\"single_label\":\".ics-Datei exportieren\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exportiere Outlook .ics Datei\",\"single_label\":\"Exportiere Outlook .ics Datei\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tAnstehende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-06\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t6\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000634 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-asmus-bremer-platz tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-kieler-innenstadt tag-flohmarkt-rathausplatz tag-holstenplatz tag-holstenstrasse tag-rathausplatz tag-willestrasse tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-06\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-6-9-2026\/\" title=\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 06.09.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 06.09.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-13\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t13\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000625 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-mettenhof tag-kaufland tag-kaufland-flohmarkt tag-kaufland-mettenhof tag-kiel tag-mettenhof tag-mettenhof-fohmarkt tag-shopping tag-skandinaviendamm tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-mettenhof tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-13\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-kiel-mettenhof-13-09-2026\/\" title=\"Flohmarkt Kaufland Kiel-Mettenhof 13.09.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kaufland Kiel-Mettenhof 13.09.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-13\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t13\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000648 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-citti-park tag-citti-park-flohmarkt tag-citti-park-kiel tag-flohmarkt tag-flohmarkt-kiel tag-hassee tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-hassee tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-13\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-13-9-2026\/\" title=\"Flohmarkt Citti-Park Kiel 13.9.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Citti-Park Kiel 13.9.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000642 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-wik tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-wik tag-flohmarkt-kiel tag-kiel tag-prinz-heinrich-strasse tag-shopping tag-wik tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping tribe_events_cat-wik gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-20-9-2026\/\" title=\"Flohmarkt famila Kiel-Wik 20.9.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Wik 20.9.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000674 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kieler-umland tag-flohmarkt-preetz tag-kreis-ploen tag-marktplatz tag-marktplatz-preetz tag-preetz tag-preetz-innenstadt tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kieler-umland tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-event-date-start\">07:00<\/span> - <span class=\"tribe-event-time\">17:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-20-09-2026\/\" title=\"Flohmarkt Preetz Innenstadt 20.09.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Preetz Innenstadt 20.09.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t20\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000669 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-gettorf tag-fussgaengerzone tag-gettorf tag-kieler-umland tag-kreis-rendsburg-eckernfoerde tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kieler-umland tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-20\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">15:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-gettorf-fussgaengerzone-20-09-2026\/\" title=\"Flohmarkt Gettorf Fu&szlig;g&auml;ngerzone 20.09.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Gettorf Fu&szlig;g&auml;ngerzone 20.09.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-27\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t27\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000635 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-asmus-bremer-platz tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-kieler-innenstadt tag-flohmarkt-rathausplatz tag-holstenplatz tag-holstenstrasse tag-rathausplatz tag-willestrasse tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-27\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kiel-innenstadt-holstenplatz-bis-rathausplatz-27-9-2026\/\" title=\"Flohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 27.09.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kiel Innenstadt Holstenplatz bis Rathausplatz 27.09.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-09-27\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tSep.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t27\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000610 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-neumeimersdorf tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-neumeimersdorf tag-flohmarkt-kiel tag-grot-steenbusch tag-kiel tag-meimersdorf tag-neumeimersdorf tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-meimersdorf tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-09-27\">\n\t\t<span class=\"tribe-event-date-start\">08:30<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-neumeimersdorf-27-9-2026\/\" title=\"Flohmarkt famila Kiel-Neumeimersdorf 27.9.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Neumeimersdorf 27.9.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-10-03\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tOkt.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t3\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000675 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kieler-umland tag-flohmarkt-preetz tag-kreis-ploen tag-marktplatz tag-marktplatz-preetz tag-preetz tag-preetz-innenstadt tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kieler-umland tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-10-03\">\n\t\t<span class=\"tribe-event-date-start\">07:00<\/span> - <span class=\"tribe-event-time\">17:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-preetz-innenstadt-03-10-2026\/\" title=\"Flohmarkt Preetz Innenstadt 03.10.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Preetz Innenstadt 03.10.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-10-03\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tOkt.\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t3\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000654 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kiel tag-flohmarkt-rewe tag-flohmarkt-rewe-kiel tag-flohmarkt-rewe-winterbeker-weg tag-hassee tag-kiel tag-rewe tag-rewe-kiel tag-rewe-winterbeker-weg tag-shopping tag-winterbeker-weg tribe_events_cat-flohmarkt tribe_events_cat-hassee tribe_events_cat-kiel tribe_events_cat-meimersdorf tribe_events_cat-shopping gallery-content-unit cat_kiel cat_kunst-und-kultur cat_weihnachtszeit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-10-03\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-rewe-center-kiel-winterbeker-weg-3-10-2026\/\" title=\"Flohmarkt REWE Center Kiel (Winterbeker Weg) 3.10.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt REWE Center Kiel (Winterbeker Weg) 3.10.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/Veranstaltungen\/\" class=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\" title=\"Weitere Veranstaltungen anzeigen.\">\n\t\tKalender anzeigen\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js=\"tribe-events-view-nonce-data\" type=\"application\/json\">{\"tvn1\":\"86342f732c\",\"tvn2\":\"\"}<\/script><div id=\"custom_html-13\" class=\"widget_text widget widget_custom_html\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"textwidget custom-html-widget\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- welovekiel_de_blog_sidebar_responsive -->\r\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-2675294892226297\" data-ad-slot=\"8830049817\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div><\/div>\n\t\t<div id=\"recent-posts-6\" class=\"widget widget_recent_entries\" style=\"border-style: solid;border-color:transparent;border-width:0px;\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Neu im Kiel-Blog<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2026-konzerte-veranstaltungen-freitag-26-06-2026-17310\/\">Kieler Woche 2026: Konzerte &amp; Veranstaltungen Freitag 26.06.2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2026-konzerte-veranstaltungen-donnerstag-25-06-2026-17308\/\">Kieler Woche 2026: Konzerte &amp; Veranstaltungen Donnerstag 25.06.2026<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/div><div id=\"encyclopedia_items-8\" class=\"widget widget_encyclopedia_items\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"heading\"><h4 class=\"widget-title\">Aus dem Kiel-Lexikon<\/h4><\/div><ul>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/norwegenkai\/\" title=\"\" class=\"encyclopedia\">Norwegenkai<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/alexander-von-humboldt-2\/\" title=\"\" class=\"encyclopedia\">Alexander von Humboldt II<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/\" title=\"\" class=\"encyclopedia\">Schlossgarten<\/a><\/li>\n    <\/ul>\n<\/div><div class=\"fusion-additional-widget-content\"><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:25% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 7.68%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 7.68%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1538,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[997,996,995,102,994,2196,2197,380,2124,379],"tribe_events_cat":[782,2029,783],"class_list":["post-11695","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-advent","tag-gut-bossee","tag-historischer-weihnachtsmarkt","tag-kieler-umland","tag-kreis-rendsburg-eckernfoerde","tag-weihnachtsbaum","tag-weihnachtsbaumverkauf","tag-weihnachtsmarkt","tag-weihnachtsmarkt-2022","tag-weihnachtszeit","tribe_events_cat-kiel","tribe_events_cat-kunst-und-kultur","tribe_events_cat-weihnachtszeit","gallery-content-unit"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Christian Gewiese\"\/>\n\t<meta name=\"keywords\" content=\"schlossgarten kiel,schlossgarten,kiel,,garten,kieler schloss,park,skulpturengarten,d\u00fcsternbrook,parkanlagen &amp; gr\u00fcnfl\u00e4chen,sehensw\u00fcrdigkeiten kiel\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"We love Kiel |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Schlossgarten Kiel | We love Kiel\" \/>\n\t\t<meta property=\"og:description\" content=\"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-09-02T23:01:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-07T22:18:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WeLoveKielCity\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Schlossgarten Kiel | We love Kiel\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/events\\\/#listItem\",\"name\":\"Veranstaltungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/events\\\/#listItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/tag\\\/kieler-umland\\\/#listItem\",\"name\":\"Kieler Umland\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/tag\\\/kieler-umland\\\/#listItem\",\"position\":3,\"name\":\"Kieler Umland\",\"item\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/tag\\\/kieler-umland\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/event\\\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\\\/#listItem\",\"name\":\"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/events\\\/#listItem\",\"name\":\"Veranstaltungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/event\\\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\\\/#listItem\",\"position\":4,\"name\":\"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/tag\\\/kieler-umland\\\/#listItem\",\"name\":\"Kieler Umland\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#organization\",\"name\":\"We love Kiel\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WeLoveKielCity\\\/\",\"https:\\\/\\\/www.instagram.com\\\/welovekiel\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/author\\\/christian\\\/#author\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/author\\\/christian\\\/\",\"name\":\"Christian Gewiese\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97707923f9bed63dfb3bbdf8065fadb426aa1508b119d1c175a90c8939cbdb88?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Christian Gewiese\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#webpage\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/\",\"name\":\"Schlossgarten Kiel | We love Kiel\",\"description\":\"Der Schlossgarten Kiel ist eine G\\u00fcnfl\\u00e4che n\\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/author\\\/christian\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/author\\\/christian\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/wp-content\\\/uploads\\\/schlossgarten-kiel-denkmal-kaiser-wilhelm.jpg\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#mainImage\",\"width\":1200,\"height\":900,\"caption\":\"Schlossgarten Kiel Kaiser-Wilhelm-Denkmal\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/lexikon\\\/schlossgarten\\\/#mainImage\"},\"datePublished\":\"2019-09-03T01:01:15+02:00\",\"dateModified\":\"2023-03-07T23:18:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"name\":\"We love Kiel\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Schlossgarten Kiel | We love Kiel","description":"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.","canonical_url":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/","robots":"max-image-preview:large","keywords":"schlossgarten kiel,schlossgarten,kiel,,garten,kieler schloss,park,skulpturengarten,d\u00fcsternbrook,parkanlagen &amp; gr\u00fcnfl\u00e4chen,sehensw\u00fcrdigkeiten kiel","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/welovekiel.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/events\/#listItem","name":"Veranstaltungen"}},{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/events\/#listItem","position":2,"name":"Veranstaltungen","item":"https:\/\/welovekiel.com\/de\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/#listItem","name":"Kieler Umland"},"previousItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/#listItem","position":3,"name":"Kieler Umland","item":"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/","nextItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/event\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\/#listItem","name":"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022"},"previousItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/events\/#listItem","name":"Veranstaltungen"}},{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/event\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\/#listItem","position":4,"name":"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022","previousItem":{"@type":"ListItem","@id":"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/#listItem","name":"Kieler Umland"}}]},{"@type":"Organization","@id":"https:\/\/welovekiel.com\/de\/#organization","name":"We love Kiel","url":"https:\/\/welovekiel.com\/de\/","sameAs":["https:\/\/www.facebook.com\/WeLoveKielCity\/","https:\/\/www.instagram.com\/welovekiel\/"]},{"@type":"Person","@id":"https:\/\/welovekiel.com\/de\/author\/christian\/#author","url":"https:\/\/welovekiel.com\/de\/author\/christian\/","name":"Christian Gewiese","image":{"@type":"ImageObject","@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/97707923f9bed63dfb3bbdf8065fadb426aa1508b119d1c175a90c8939cbdb88?s=96&d=mm&r=g","width":96,"height":96,"caption":"Christian Gewiese"}},{"@type":"WebPage","@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#webpage","url":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/","name":"Schlossgarten Kiel | We love Kiel","description":"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/welovekiel.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#breadcrumblist"},"author":{"@id":"https:\/\/welovekiel.com\/de\/author\/christian\/#author"},"creator":{"@id":"https:\/\/welovekiel.com\/de\/author\/christian\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/welovekiel.com\/wp-content\/uploads\/schlossgarten-kiel-denkmal-kaiser-wilhelm.jpg","@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#mainImage","width":1200,"height":900,"caption":"Schlossgarten Kiel Kaiser-Wilhelm-Denkmal"},"primaryImageOfPage":{"@id":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/#mainImage"},"datePublished":"2019-09-03T01:01:15+02:00","dateModified":"2023-03-07T23:18:06+01:00"},{"@type":"WebSite","@id":"https:\/\/welovekiel.com\/de\/#website","url":"https:\/\/welovekiel.com\/de\/","name":"We love Kiel","inLanguage":"de-DE","publisher":{"@id":"https:\/\/welovekiel.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"We love Kiel |","og:type":"article","og:title":"Schlossgarten Kiel | We love Kiel","og:description":"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt.","og:url":"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/","article:published_time":"2019-09-02T23:01:15+00:00","article:modified_time":"2023-03-07T22:18:06+00:00","article:publisher":"https:\/\/www.facebook.com\/WeLoveKielCity\/","twitter:card":"summary","twitter:title":"Schlossgarten Kiel | We love Kiel","twitter:description":"Der Schlossgarten Kiel ist eine G\u00fcnfl\u00e4che n\u00f6rdlich des Kieler Schlosses und wurde als Renaissancegarten im 16. Jahhundert beim Schlossausbau zum Renaissancesitz angelegt."},"aioseo_meta_data":{"post_id":"11695","title":null,"description":"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 2022 am Samstag, den 10. Dezember 2022 - Der Weihnachtsmarkt auf Gut Bossee z\u00e4hlt zu einem der sch\u00f6nsten Weihnachtsm\u00e4rkte im Kieler Umland.","keywords":[],"keyphrases":{"focus":{"keyphrase":"Gut Bossee","score":88,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase does not appear in the first paragraph. Make sure the topic is clear immediately.","score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"title":"Focus keyphrase in Subheadings","description":"Your H2 and H3 subheadings reflects the topic of your copy. Good job!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[]}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-11-08 16:55:07","updated":"2022-11-09 07:57:54","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/events\/\" title=\"Veranstaltungen\">Veranstaltungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/\" title=\"Kieler Umland\">Kieler Umland<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHistorischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/welovekiel.com\/de\/"},{"label":"Veranstaltungen","link":"https:\/\/welovekiel.com\/de\/events\/"},{"label":"Kieler Umland","link":"https:\/\/welovekiel.com\/de\/tag\/kieler-umland\/"},{"label":"Historischer Weihnachtsmarkt Gut Bossee 3. Adventssamstag 10.12.2022","link":"https:\/\/welovekiel.com\/de\/event\/historischer-weihnachtsmarkt-gut-bossee-3-adventssamstag-10-12-2022\/"}],"_links":{"self":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events\/11695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events\/11695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media\/1538"}],"wp:attachment":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media?parent=11695"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tags?post=11695"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=11695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}