{"id":15684,"date":"2024-01-05T08:26:56","date_gmt":"2024-01-05T07:26:56","guid":{"rendered":"https:\/\/welovekiel.com\/?post_type=gallery&#038;p=15684"},"modified":"2024-01-05T08:26:56","modified_gmt":"2024-01-05T07:26:56","slug":"silvester-2023-an-der-kieler-foerde","status":"publish","type":"gallery","link":"https:\/\/welovekiel.com\/de\/galleries\/silvester-2023-an-der-kieler-foerde\/","title":{"rendered":"Silvester 2023 an der Kieler F\u00f6rde"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\"><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_3_4 3_4 fusion-three-fourth fusion-column-first\" style=\"width:75%;width:calc(75% - ( ( 4% ) * 0.75 ) );margin-right: 4%;margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\"><p><strong>Bildergalerie Silvester 2023 an der <a href=\"https:\/\/welovekiel.com\/de\/lexikon\/kieler-foerde\/\" target=\"_self\" title=\"\" class=\"encyclopedia\">Kieler F&ouml;rde<\/a> Feuerwerk in der Silvesternacht vom 31.12.2023 auf den 01.01.2024.<\/strong><\/p>\n<p>Nachfolgend gibt es einige Fotos und Videos von dem Silvester Feuerwerk 2023 in Kiel, aufgenommen von der Reventloubr&uuml;cke. Zahlreiche Menschen sind in der Silvesternacht zur <a href=\"https:\/\/welovekiel.com\/de\/lexikon\/kiellinie-kiel\/\" target=\"_self\" title=\"\" class=\"encyclopedia\">Kiellinie<\/a> an die Kieler F&ouml;rde gekommen, um hier an der beliebten Uferpromenade an der F&ouml;rde ihr Feuerwerk um Mitternacht zu z&uuml;nden. Oer einfach auch nur, um das Feuerwerk der anderen zu genie&szlig;en. Von der Reventloubr&uuml;cke hatte man einen guten Blick auf einen weiten Bereich der Kiellinie und die gegen&uuml;berliegende Reventlouwiese.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id=\"gallery-1\" class=\"gallery galleryid-15684 gallery-columns-2 gallery-size-fusion-400\"><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Moby Kiel Kiellinie am Abend\" data-caption=\"Moby Kiel Kiellinie am Abend\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends.jpg\" title=\"Moby Kiel Kiellinie am Abend\" data-description=\"Moby Kiel Kiellinie am Abend\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Moby Kiel Kiellinie am Abend\" aria-describedby=\"gallery-1-15655\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/moby-kiel-kiellinie-abends.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15655\">\n\t\t\t\tMoby Kiel Kiellinie am Abend\n\t\t\t\t<\/dd><\/dl><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Silvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\" data-caption=\"Silvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24.jpg\" title=\"Silvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\" data-description=\"Silvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Silvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\" aria-describedby=\"gallery-1-15651\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-kiel-kiellinie-rauch-feuerwerk-2023-24.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15651\">\n\t\t\t\tSilvester Kiel Kiellinie Rauch und Feuerwerk 2023\/2024\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\"><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Silvester Feuerwerk Kiel Kiellinie Reventlouwiese\" data-caption=\"Silvester Feuerwerk Kiel Kiellinie Reventlouwiese\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese.jpg\" title=\"Silvester Feuerwerk Kiel Kiellinie Reventlouwiese\" data-description=\"Silvester Feuerwerk Kiel Kiellinie Reventlouwiese\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Silvester Feuerwerk Kiel Kiellinie Reventlouwiese\" aria-describedby=\"gallery-1-15649\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventlouwiese.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15649\">\n\t\t\t\tSilvester Feuerwerk Kiel Kiellinie Reventlouwiese\n\t\t\t\t<\/dd><\/dl><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Silvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\" data-caption=\"Silvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke.jpg\" title=\"Silvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\" data-description=\"Silvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Silvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\" aria-describedby=\"gallery-1-15647\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/silvester-feuerwerk-kiel-kiellinie-reventloubruecke.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15647\">\n\t\t\t\tSilvester Feuerwerk Kiel Kiellinie Reventloubr&uuml;cke\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\"><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Reventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\" data-caption=\"Reventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie.jpg\" title=\"Reventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\" data-description=\"Reventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Reventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\" aria-describedby=\"gallery-1-15645\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/reventloubruecke-kieler-foerde-kiellinie.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15645\">\n\t\t\t\tReventloubr&uuml;cke Kieler F&ouml;rde Silvesternacht\n\t\t\t\t<\/dd><\/dl><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Kiel Reventlouwiese \/ Kiellinie Silvester 2023\" data-caption=\"Kiel Reventlouwiese \/ Kiellinie Silvester 2023\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24.jpg\" title=\"Kiel Reventlouwiese \/ Kiellinie Silvester 2023\" data-description=\"Kiel Reventlouwiese \/ Kiellinie Silvester 2023\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Kiel Reventlouwiese \/ Kiellinie Silvester 2023\" aria-describedby=\"gallery-1-15643\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiel-reventlouwiese-kiellinie-silvester-2023-24.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15643\">\n\t\t\t\tKiel Reventlouwiese \/ Kiellinie Silvester 2023\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\"><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Silvester 2023 M&uuml;ll an der Kiellinie\" data-caption=\"Silvester 2023 M&uuml;ll an der Kiellinie\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell.jpg\" title=\"Silvester 2023 M&uuml;ll an der Kiellinie\" data-description=\"Silvester 2023 M&uuml;ll an der Kiellinie\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Silvester 2023 M&uuml;ll an der Kiellinie\" aria-describedby=\"gallery-1-15641\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-muell.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15641\">\n\t\t\t\tSilvester 2023 M&uuml;ll an der Kiellinie\n\t\t\t\t<\/dd><\/dl><dl class=\"gallery-item\">\n\t\t\t<dt class=\"gallery-icon landscape\">\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"Kiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\" data-caption=\"Kiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\" href=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke.jpg\" title=\"Kiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\" data-description=\"Kiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\"><img decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-400x300.jpg\" class=\"attachment-fusion-400 size-fusion-400 lazyload\" alt=\"Kiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\" aria-describedby=\"gallery-1-15639\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27900%27%20viewBox%3D%270%200%201200%20900%27%3E%3Crect%20width%3D%271200%27%20height%3D%27900%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-400x300.jpg\" data-srcset=\"https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-200x150.jpg 200w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-300x225.jpg 300w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-400x300.jpg 400w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-600x450.jpg 600w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-768x576.jpg 768w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-800x600.jpg 800w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke-1024x768.jpg 1024w, https:\/\/welovekiel.com\/wp-content\/uploads\/kiellinie-kiel-silvester-2023-24-reventloubruecke.jpg 1200w\" data-sizes=\"auto\"><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class=\"wp-caption-text gallery-caption\" id=\"gallery-1-15639\">\n\t\t\t\tKiellinie Kiel Silvester 2023 Blick von der Reventloubr&uuml;cke\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\">\n\t\t<\/div>\n\n<\/div><style type=\"text\/css\">@media only screen and (max-width:800px) {.fusion-title.fusion-title-1{margin-top:10px!important;margin-bottom:!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\" style=\"margin-top:20px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><h2 class=\"title-heading-left\" style=\"margin:0;\">Dies k&ouml;nnte dich auch interessieren<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><ul class=\"posts-by-tag-list\"><li class=\"posts-by-tag-item Fireworks Kiel Fjord Kiellinie New Year's Eve Party Reventloubr&uuml;cke Reventlouwiese Weco\" id=\"posts-by-tag-item-15678\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/en\/new-yeras-eve-fireworks-kiel-kiellinie-2023-15678\/\">New Year's Eve fireworks 2023 at the Kiellinie Kiel<\/a> <small>Posted on: 1. Januar 2024<\/small><\/li><li class=\"posts-by-tag-item Feuerwerk Kieler F&ouml;rde Kiellinie Party Reventloubr&uuml;cke Reventlouwiese Silvester Weco\" id=\"posts-by-tag-item-15665\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/silvester-feuerwerk-2023-kiellinie-kiel-kieler-foerde-15665\/\">Silvester Feuerwerk 2023 an der Kiellinie Kiel<\/a> <small>Posted on: 1. Januar 2024<\/small><\/li><li class=\"posts-by-tag-item Drohnenshow Fackelschwimmer Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2023 Kieler Woche Feuerwerk Kiellinie Lasershow Sternenzauber\" id=\"posts-by-tag-item-15290\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-feuerwerk-2023-15290\/\">Kieler Woche Feuerwerk 2023 mit Laser, Drohnen und James Bond Musik<\/a> <small>Posted on: 26. Juni 2023<\/small><\/li><li class=\"posts-by-tag-item F&ouml;rdeb&uuml;hne Kieler Woche Kieler Woche 2023 Kieler Woche Konzert Kiellinie Konzert Konzerte Pirate World Radio Bob! Rockcamp Rathausb&uuml;hne Together Kiel Woderkant Festival\" id=\"posts-by-tag-item-15277\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2023-konzerte-am-samstag-24-06-2023-15277\/\">Kieler Woche 2023: Konzerte am Samstag 24.06.2023<\/a> <small>Posted on: 24. Juni 2023<\/small><\/li><li class=\"posts-by-tag-item AIDA D&uuml;sternbrook Fackelschwimmer Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2022 Kieler Woche Feuerwerk Kiellinie Ostseekai Sternenzauber\" id=\"posts-by-tag-item-10702\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-feuerwerk-2022-sternenzauber-ueber-kiel-10702\/\">Kieler Woche Feuerwerk 2022 Sternenzauber &uuml;ber Kiel<\/a> <small>Posted on: 27. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Deine Cousine Kieler Woche Kieler Woche 2022 Kieler Woche Konzert Kiellinie Konzert Radio Bob! Rockcamp Reventlouwiese Rockband\" id=\"posts-by-tag-item-10753\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/deine-cousine-live-auf-der-kieler-woche-am-25-6-2022-10753\/\">Deine Cousine live auf der Kieler Woche am 25.6.2022<\/a> <small>Posted on: 26. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Fackelschwimmer Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2022 Kieler Woche Feuerwerk Kiellinie Reventloubr&uuml;cke Sternenzauber\" id=\"posts-by-tag-item-10665\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-feuerwerk-2022-sternenzauber-ueber-kiel-am-sonntagabend-10665\/\">Kieler Woche Feuerwerk 2022 \"Sternenzauber &uuml;ber Kiel\" am Sonntagabend<\/a> <small>Posted on: 26. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Feuerwerk Kieler Woche Kieler Woche 2022 Kieler Woche Feuerwerk Olympiahafen Schilksee Olympiazentrum Schilksee Schilksee Strand Segelfeuerwerk\" id=\"posts-by-tag-item-10620\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-segelfeuerwerk-2022-schilksee-21-6-2022-10620\/\">Kieler Woche Segelfeuerwerk 2022 in Schilksee am 21.6.2022<\/a> <small>Posted on: 22. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2022 Kieler Woche Feuerwerk Nordmarksportfeld Olympiazentrum Schilksee Schilksee Segelfeuerwerk\" id=\"posts-by-tag-item-10320\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2022-feuerwerk-termine-10320\/\">Kieler Woche 2022 Feuerwerk Termine Abschlussfeuerwerk, Segelfeuerwerk und Nordmarksportfeld<\/a> <small>Posted on: 12. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Cotidiano D&uuml;sternbrook Kieler F&ouml;rde Kiellinie Moby Nordwind Pfingsten Pfingstsonntag Reventloubr&uuml;cke Reventlouwiese SFK SFK Kiel\" id=\"posts-by-tag-item-10223\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/pfingstsonntag-an-der-kiellinie-kiel-10223\/\">Pfingstsonntag an der Kiellinie Kiel<\/a> <small>Posted on: 6. Juni 2022<\/small><\/li><li class=\"posts-by-tag-item Deutsche Marine Gorch Fock Gorch-Fock-Mole Kieler F&ouml;rde Kiellinie Marineschiffe Marinest&uuml;tzpunkt Kiel-Wik Schiffe Segelschiff\" id=\"posts-by-tag-item-8456\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/segelschulschiff-gorch-fock-zurueck-im-heimathafen-kiel-8456\/\">Segelschulschiff Gorch Fock zur&uuml;ck im Heimathafen Kiel<\/a> <small>Posted on: 25. M&auml;rz 2022<\/small><\/li><li class=\"posts-by-tag-item Boern Kiellinie Kunst Kunstkollektiv Kunstprojekt\" id=\"posts-by-tag-item-8158\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kunstkollektiv-boern-verschenkt-100-muetzen-an-der-kiellinie-8158\/\">Kunstkollektiv B&oelig;rn verschenkt 100 M&uuml;tzen an der Kiellinie<\/a> <small>Posted on: 27. Februar 2022<\/small><\/li><li class=\"posts-by-tag-item AIDA AIDA Cruises AIDAcosma Erstauslauf Kieler F&ouml;rde Kieler Hafen Kiellinie Kreuzfahrtschiffe Ostseekai Reventloubr&uuml;cke Schiffe\" id=\"posts-by-tag-item-8094\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/aidacosma-verlaesst-kiel-8094\/\">AIDAcosma verl&auml;sst Kiel<\/a> <small>Posted on: 23. Februar 2022<\/small><\/li><li class=\"posts-by-tag-item Deutsche Marine D&uuml;sternbrook Gorch Fock Gorch-Fock-Mole Kieler F&ouml;rde Kiellinie Marineschiffe Marinest&uuml;tzpunkt Kiel-Wik Segelschiffe Segelschulschiff Wik\" id=\"posts-by-tag-item-7319\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/segelschulschiff-gorch-fock-ist-zurueck-in-kiel-7319\/\">Segelschulschiff Gorch Fock ist zur&uuml;ck in Kiel<\/a> <small>Posted on: 5. Oktober 2021<\/small><\/li><li class=\"posts-by-tag-item Kieler F&ouml;rde Kiellinie Sturm Tornado Unwetter Wetter\" id=\"posts-by-tag-item-7181\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/videos-tornado-in-kiel-2021-unwetter-kiellinie-7181\/\">Videos: TORNADO in Kiel 29.09.2021 Unwetter Uferpromenade Kiellinie an der Kieler F&ouml;rde<\/a> <small>Posted on: 30. September 2021<\/small><\/li><li class=\"posts-by-tag-item AIDA Drohnenshow Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2021 Kieler Woche Feuerwerk Kiellinie Sternenzauber\" id=\"posts-by-tag-item-7139\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-feuerwerk-2021-drohnen-show-7139\/\">Kieler Woche Feuerwerk 2021 mit Drohnen Show<\/a> <small>Posted on: 14. September 2021<\/small><\/li><li class=\"posts-by-tag-item Feuerwerk Kieler Woche Kieler Woche 2021 Kieler Woche Feuerwerk Olympiahafen Schilksee Olympiazentrum Schilksee Schilksee Segelfeuerwerk\" id=\"posts-by-tag-item-6906\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-segelfeuerwerk-schilksee-2021-6906\/\">Kieler Woche Segelfeuerwerk in Schilksee am 07.09.2021<\/a> <small>Posted on: 8. September 2021<\/small><\/li><li class=\"posts-by-tag-item 2021 Drohnenshow Fackelschwimmer Feuerwerk Kieler F&ouml;rde Kieler Woche Kieler Woche 2021 Kieler Woche Feuerwerk Kiellinie\" id=\"posts-by-tag-item-6050\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2021-feuerwerk-sternenzauber-ueber-kiel-mit-drohnenshow-6050\/\">Kieler Woche 2021: Feuerwerk \"Sternenzauber &uuml;ber Kiel\" mit Drohnenshow &amp; Fackelschwimmern<\/a> <small>Posted on: 26. August 2021<\/small><\/li><li class=\"posts-by-tag-item Corona COVID-19 Kieler Woche Kieler Woche 2021 Kiellinie Konzerte Windjammerparade\" id=\"posts-by-tag-item-5417\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kieler-woche-2021-absage-veranstaltungen-an-land-5417\/\">Kieler Woche 2021: Absage aller gro&szlig;en Veranstaltungen an Land!<\/a> <small>Posted on: 31. Juli 2021<\/small><\/li><li class=\"posts-by-tag-item Corona Cotidiano COVID-19 D&uuml;sternbrook Gastronomie Gosch Kieler F&ouml;rde Kiellinie Promenade\" id=\"posts-by-tag-item-4978\"><a class=\"posts-by-tag-item-title\" href=\"https:\/\/welovekiel.com\/de\/kiellinie-kieler-foerde-april-2021-4978\/\">Kiellinie: Beliebtes Ausflugsziel an der Kieler F&ouml;rde am Sonntagnachmittag<\/a> <small>Posted on: 19. April 2021<\/small><\/li><\/ul>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:800px) {.fusion-title.fusion-title-2{margin-top:10px!important;margin-bottom:!important;}}<\/style><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-two\" style=\"margin-top:20px;margin-right:0px;margin-bottom:31px;margin-left:0px;\"><h2 class=\"title-heading-left\" style=\"margin:0;\">Videos Silvester Feuerwerk in Kiel an der Kieler F&ouml;rde<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 1\" src=\"https:\/\/www.youtube.com\/embed\/5E1iymbtFU8?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-section-separator section-separator slant fusion-section-separator-1\"><div class=\"fusion-section-separator-svg\" style=\"padding:0;margin-left: 0px;margin-right: 0px;\"><svg class=\"fusion-slant-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" height=\"100\" viewbox=\"0 0 100 100\" preserveaspectratio=\"none\" style=\"padding:0;\" fill=\"rgba(246,246,246,1)\"><path d=\"M100 0 L100 100 L0 0 Z\"><\/path><\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\" style=\"height:99px;\"><\/div><\/div><style type=\"text\/css\">.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg svg,.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-svg-bg{height:5px;}.fusion-section-separator.fusion-section-separator-1 .fusion-section-separator-spacer-height{height:5px !important;padding-top:inherit !important;}<\/style><\/div><div class=\"fusion-video fusion-youtube\" style=\"max-width:800px;max-height:450px;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:56.25%;\"><iframe title=\"YouTube video player 2\" src=\"https:\/\/www.youtube.com\/embed\/iRDv6BUgHNs?wmode=transparent&amp;autoplay=0\" width=\"800\" height=\"450\" allowfullscreen allow=\"autoplay; fullscreen\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"width:25%;width:calc(25% - ( ( 4% ) * 0.25 ) );margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-widget-area fusion-widget-area-1 fusion-content-widget-area\"><style type=\"text\/css\">.fusion-widget-area-1 {padding:0px 0px 0px 0px;}.fusion-widget-area-1 .widget h4 {color:#333333;}.fusion-widget-area-1 .widget .heading h4 {color:#333333;}<\/style><div id=\"custom_html-11\" class=\"widget_text widget widget_custom_html\"><div class=\"textwidget custom-html-widget\"><script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- welovekiel_de_galerie_sidebar_responsive -->\r\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-2675294892226297\" data-ad-slot=\"5973548078\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script><\/div><\/div><div id=\"gallery-taxonomies-2\" class=\"widget widget_gallery-taxonomies\" style=\"border-style: solid;border-color:transparent;border-width:0px;\"><div class=\"heading\"><h4 class=\"widget-title\">Kategorien der Bildergalerien<\/h4><\/div>\n<ul>\n  \t<li class=\"cat-item cat-item-339\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/veranstaltungen-events\/\">Veranstaltungen &amp; Events<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-277\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kieler-foerde\/\">Kieler F&ouml;rde<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-293\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/schiffe\/\">Schiffe<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-276\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kieler-woche\/\">Kieler Woche<\/a>\n<ul class=\"children\">\n\t<li class=\"cat-item cat-item-301\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kieler-woche-konzerte\/\">Kieler Woche Konzerte<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-533\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kieler-hafen\/\">Kieler Hafen<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-501\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/wik\/\">Wik<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-401\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/altstadt\/\">Altstadt<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-674\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/sehenswuerdigkeiten\/\">Sehensw&uuml;rdigkeiten<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-402\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/vorstadt\/\">Vorstadt<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-502\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/duesternbrook\/\">D&uuml;sternbrook<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-311\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/musik-konzerte\/\">Musik &amp; Konzerte<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-890\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/gebaeude-bauwerke\/\">Geb&auml;ude &amp; Bauwerke<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-318\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/straende\/\">Str&auml;nde<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-573\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/schilksee\/\">Schilksee<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-476\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/parkanlagen-gruenflaechen\/\">Parkanlagen &amp; Gr&uuml;nfl&auml;chen<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-648\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/holtenau\/\">Holtenau<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-672\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kieler-umland\/\">Kieler Umland<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-673\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/kreis-rendsburg-eckernfoerde\/\">Kreis Rendsburg-Eckernf&ouml;rde<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-844\"><a href=\"https:\/\/welovekiel.com\/de\/galleries\/category\/sport\/\">Sport<\/a>\n<\/li>\n<\/ul>\n\n<\/div><div id=\"encyclopedia_items-6\" class=\"widget widget_encyclopedia_items\"><div class=\"heading\"><h4 class=\"widget-title\">Aus dem Kiel Lexikon<\/h4><\/div><ul>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/schlossgarten\/\" title=\"\" class=\"encyclopedia\">Schlossgarten<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/rathausplatz-kiel\/\" title=\"\" class=\"encyclopedia\">Rathausplatz<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/kiel-duesternbrook\/\" title=\"\" class=\"encyclopedia\">D&uuml;sternbrook<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/leuchtturm-friedrichsort\/\" title=\"\" class=\"encyclopedia\">Leuchtturm Friedrichsort<\/a><\/li>\n            <li><a href=\"https:\/\/welovekiel.com\/de\/lexikon\/norwegenkai\/\" title=\"\" class=\"encyclopedia\">Norwegenkai<\/a><\/li>\n    <\/ul>\n<\/div>\n\t\t<div id=\"recent-posts-4\" class=\"widget widget_recent_entries\">\n\t\t<div class=\"heading\"><h4 class=\"widget-title\">Neu im Kiel Blog<\/h4><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/buehnenaufbau-holstein-kiel-aufstiegsparty-rathausplatz-16867\/\">B&uuml;hnenaufbau Holstein Kiel Aufstiegsparty Rathausplatz Sonntagnachmittag<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/holstein-kiel-bundesliga-fans-holstein-stadion-16835\/\">Holstein Kiel Bundesliga Aufstiegsparty am Holstein-Stadion nach Unentschieden gegen D&uuml;sseldorf<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/holstein-kiel-fans-fanmarsch-zum-holstein-stadion-16832\/\">Holstein Kiel Fans: Fanmarsch von Forstbaumschule zum Holstein-Stadion vor letztem Heimspiel gegen D&uuml;sseldorf<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/neue-sfk-elektrofaehre-ms-dietrichsdorf-16638\/\">Neue SFK Elektrof&auml;hre MS Dietrichsdorf in Kiel eingetroffen<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/welovekiel.com\/de\/kiel-cherson-staedtepartnerschaft-16629\/\">Kiel schlie&szlig;t St&auml;dtepartnerschaft mit Cherson<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/div><div class=\"tribe-compatibility-container\">\n\t<div class=\"tribe-common tribe-events tribe-events-view tribe-events-view--widget-events-list tribe-events-widget\" data-js=\"tribe-events-view\" data-view-rest-url=\"https:\/\/welovekiel.com\/de\/wp-json\/tribe\/views\/v2\/html\" data-view-manage-url=\"1\" data-view-breakpoint-pointer=\"ce4da0e0-45ac-40e6-a187-5eb4f0ec7552\">\n\t\t<div class=\"tribe-events-widget-events-list\">\n\n\t\t\t<script type=\"application\/ld+json\">\r\n[{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt Kaufland Schwentinental \/ Raisdorf am Donnerstag, den 14. Mai 2026 ab 8.00 Uhr auf dem Kaufland Parkplatz in der Mergenthalerstra\\u00dfe (ehemals real). Am 14.05.2026 veranstaltet Hochberg Flohm\\u00e4rkte einen gro\\u00dfen Flohmarkt auf dem Kaufland Parkplatz [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-verkaufsstand-figuren-sammeln.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-14T08:00:00+02:00\",\"endDate\":\"2026-05-14T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Kaufland Schwentinental\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/kaufland-schwentinental\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Mergenthalerstra\\u00dfe 13-21\",\"addressLocality\":\"Schwentinental\",\"postalCode\":\"24223\",\"addressCountry\":\"Germany\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt famila Kiel-Wik 17.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt famila Kiel-Wik am Sonntag, den 17. Mai 2026 ab 6 Uhr auf dem famila Parkplatz im Kieler Stadtteil Wik in der Prinz-Heinrich-Stra\\u00dfe. In den Monaten M\\u00e4rz bis Oktober 2026 veranstaltet Heinz Geide Flohm\\u00e4rkte insgesamt [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/famila-flohmarkt-kiel-wik.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-17T06:00:00+02:00\",\"endDate\":\"2026-05-17T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"famila Kiel-Wik\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/famila-kiel-wik\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Prinz-Heinrich-Stra\\u00dfe 20\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24106\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Heinz Geide Flom\\u00e4rkte\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"},{\"@context\":\"http:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"Flohmarkt Citti-Park Kiel 17.5.2026\",\"description\":\"&lt;p&gt;Flohmarkt Citti-Park Kiel am Sonntag, den 17. Mai 2026 ab 8 Uhr auf dem Citti-Park Parkplatz im M\\u00fchlendamm 1 im Kieler Stadtteil Hassee. An insgesamt sechs Terminen im Jahr 2026 veranstaltet die Firma Hochberg Flohm\\u00e4rkte [&hellip;]&lt;\/p&gt;\\\\n\",\"image\":\"https:\/\/welovekiel.com\/wp-content\/uploads\/flohmarkt-kiel-citti-park.jpg\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"eventStatus\":\"https:\/\/schema.org\/EventScheduled\",\"startDate\":\"2026-05-17T08:00:00+02:00\",\"endDate\":\"2026-05-17T16:00:00+02:00\",\"location\":{\"@type\":\"Place\",\"name\":\"Citti-Park Kiel\",\"description\":\"\",\"url\":\"https:\/\/welovekiel.com\/de\/veranstaltungsort\/citti-park-kiel\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"M\\u00fchlendamm 1\",\"addressLocality\":\"Kiel\",\"postalCode\":\"24113\",\"addressCountry\":\"Deutschland\"},\"telephone\":\"\",\"sameAs\":\"\"},\"organizer\":{\"@type\":\"Person\",\"name\":\"Hochberg Flohmarkt\",\"description\":\"\",\"url\":\"\",\"telephone\":\"\",\"email\":\"\",\"sameAs\":\"\"},\"offers\":{\"@type\":\"Offer\",\"price\":\"0\",\"priceCurrency\":\"EUR\",\"url\":\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\",\"category\":\"primary\",\"availability\":\"inStock\",\"validFrom\":\"1970-01-01T00:00:00+00:00\"},\"performer\":\"Organization\"}]\r\n<\/script>\n\t\t\t<script data-js=\"tribe-events-view-data\" type=\"application\/json\">\n\t{\"slug\":\"widget-events-list\",\"prev_url\":\"\",\"next_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&paged=2\",\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Widgets\\\\Widget_List_View\",\"view_slug\":\"widget-events-list\",\"view_label\":\"View\",\"view\":null,\"should_manage_url\":true,\"id\":null,\"alias-slugs\":null,\"title\":\"Veranstaltungen von 14. Mai \\u2013 17. Mai \\u2013 We love Kiel\",\"limit\":\"3\",\"no_upcoming_events\":false,\"featured_events_only\":false,\"jsonld_enable\":true,\"tribe_is_list_widget\":false,\"admin_fields\":{\"title\":{\"label\":\"Titel:\",\"type\":\"text\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-title\",\"name\":\"widget-tribe-widget-events-list[6][title]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"limit\":{\"label\":\"Anzeige:\",\"type\":\"number\",\"default\":5,\"min\":1,\"max\":10,\"step\":1,\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-limit\",\"name\":\"widget-tribe-widget-events-list[6][limit]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"metadata_section\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-checkbox-group\",\"label\":\"Anzeige:\",\"children\":{\"cost\":{\"type\":\"checkbox\",\"label\":\"Preis\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-cost\",\"name\":\"widget-tribe-widget-events-list[6][cost]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"venue\":{\"type\":\"checkbox\",\"label\":\"Veranstaltungsort\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-venue\",\"name\":\"widget-tribe-widget-events-list[6][venue]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"street\":{\"type\":\"checkbox\",\"label\":\"Stra\\u00dfe\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-street\",\"name\":\"widget-tribe-widget-events-list[6][street]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"city\":{\"type\":\"checkbox\",\"label\":\"Stadt\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-city\",\"name\":\"widget-tribe-widget-events-list[6][city]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"region\":{\"type\":\"checkbox\",\"label\":\"Staat (USA) oder Bundesland \\\/ Kanton (International)\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-region\",\"name\":\"widget-tribe-widget-events-list[6][region]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"zip\":{\"type\":\"checkbox\",\"label\":\"Postleitzahl\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-zip\",\"name\":\"widget-tribe-widget-events-list[6][zip]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"country\":{\"type\":\"checkbox\",\"label\":\"Land\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-country\",\"name\":\"widget-tribe-widget-events-list[6][country]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"phone\":{\"type\":\"checkbox\",\"label\":\"Telefon\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-phone\",\"name\":\"widget-tribe-widget-events-list[6][phone]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"organizer\":{\"type\":\"checkbox\",\"label\":\"Veranstalter\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-organizer\",\"name\":\"widget-tribe-widget-events-list[6][organizer]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"website\":{\"type\":\"checkbox\",\"label\":\"Webseite\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-website\",\"name\":\"widget-tribe-widget-events-list[6][website]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-metadata_section\",\"name\":\"widget-tribe-widget-events-list[6][metadata_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy_section\":{\"type\":\"section\",\"classes\":[\"calendar-widget-filters-container\"],\"label\":\"Filter:\",\"children\":{\"filters\":{\"type\":\"taxonomy-filters\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-filters\",\"label\":\"\",\"name\":\"widget-tribe-widget-events-list[6][filters]\",\"options\":[],\"placeholder\":\"\",\"value\":null,\"list_items\":[]},\"operand\":{\"type\":\"fieldset\",\"classes\":\"tribe-common-form-control-checkbox-radio-group\",\"label\":\"Operand:\",\"selected\":\"OR\",\"children\":[{\"type\":\"radio\",\"label\":\"Match any\",\"button_value\":\"OR\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-operand\",\"name\":\"widget-tribe-widget-events-list[6][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null},{\"type\":\"radio\",\"label\":\"Match all\",\"button_value\":\"AND\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-operand\",\"name\":\"widget-tribe-widget-events-list[6][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}],\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-operand\",\"name\":\"widget-tribe-widget-events-list[6][operand]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-taxonomy_section\",\"name\":\"widget-tribe-widget-events-list[6][taxonomy_section]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"taxonomy\":{\"type\":\"taxonomy\",\"classes\":\"calendar-widget-add-filter\",\"label\":\"Filter zuf\\u00fcgen:\",\"placeholder\":\"W\\u00e4hle einen Taxonomiebegriff\",\"parent_classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-taxonomy\",\"name\":\"widget-tribe-widget-events-list[6][taxonomy]\",\"options\":[],\"value\":null},\"no_upcoming_events\":{\"label\":\"Blende dieses Widget aus, wenn es keine bevorstehenden Veranstaltungen gibt.\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-no_upcoming_events\",\"name\":\"widget-tribe-widget-events-list[6][no_upcoming_events]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"featured_events_only\":{\"label\":\"Nur auf hervorgehobene Veranstaltungen beschr\\u00e4nken\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-featured_events_only\",\"name\":\"widget-tribe-widget-events-list[6][featured_events_only]\",\"options\":[],\"placeholder\":\"\",\"value\":null},\"jsonld_enable\":{\"label\":\"JSON-LD-Daten generieren\",\"type\":\"checkbox\",\"parent_classes\":\"\",\"classes\":\"\",\"dependency\":\"\",\"id\":\"widget-tribe-widget-events-list-6-jsonld_enable\",\"name\":\"widget-tribe-widget-events-list[6][jsonld_enable]\",\"options\":[],\"placeholder\":\"\",\"value\":null}},\"venue\":false,\"country\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"phone\":false,\"cost\":false,\"organizer\":false,\"website\":false,\"operand\":\"OR\",\"filters\":\"\",\"wpml_language\":\"de\",\"fusion_display_title\":\"yes\",\"fusion_padding_color\":\"\",\"fusion_margin\":\"\",\"fusion_bg_color\":\"\",\"fusion_bg_radius_size\":\"\",\"fusion_border_size\":\"\",\"fusion_border_style\":\"solid\",\"fusion_border_color\":\"\",\"fusion_divider_color\":\"\",\"fusion_align\":\"\",\"fusion_align_mobile\":\"\",\"events\":[10000655,10000638,10000646],\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list\",\"url_event_date\":false,\"bar\":{\"keyword\":\"\",\"date\":\"\"},\"today\":\"2026-05-14 00:00:00\",\"now\":\"2026-05-14 00:59:31\",\"home_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/\",\"rest_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/wp-json\\\/tribe\\\/views\\\/v2\\\/html\",\"rest_method\":\"GET\",\"rest_nonce\":\"\",\"today_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&eventDisplay=widget-events-list&rest_route=%2Fwp%2Fv2%2Fgallery%2F15684\",\"today_title\":\"Klicke, um das heutige Datum auszuw\\u00e4hlen\",\"today_label\":\"Heute\",\"prev_label\":\"\",\"next_label\":\"\",\"date_formats\":{\"compact\":\"d.m.Y\",\"month_and_year_compact\":\"m.Y\",\"month_and_year\":\"F Y\",\"time_range_separator\":\" - \",\"date_time_separator\":\" | \"},\"messages\":[],\"start_of_week\":\"1\",\"header_title\":\"\",\"header_title_element\":\"h1\",\"content_title\":\"\",\"breadcrumbs\":[],\"backlink\":false,\"before_events\":\"\",\"after_events\":\"\\n<!--\\nThis calendar is powered by The Events Calendar.\\nhttp:\\\/\\\/evnt.is\\\/18wn\\n-->\\n\",\"display_events_bar\":false,\"disable_event_search\":false,\"live_refresh\":true,\"ical\":{\"display_link\":true,\"link\":{\"url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/?post_type=tribe_events&#038;eventDisplay=widget-events-list&#038;ical=1\",\"text\":\"Veranstaltungen als iCal exportieren\",\"title\":\"Diese Funktion verwenden, um Kalenderdaten mit Google Kalender, Apple iCal und kompatiblen Apps zu teilen\"}},\"container_classes\":[\"tribe-common\",\"tribe-events\",\"tribe-events-view\",\"tribe-events-view--widget-events-list\",\"tribe-events-widget\"],\"container_data\":[],\"is_past\":false,\"breakpoints\":{\"xsmall\":500,\"medium\":768,\"full\":960},\"breakpoint_pointer\":\"ce4da0e0-45ac-40e6-a187-5eb4f0ec7552\",\"is_initial_load\":false,\"public_views\":{\"list\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\List_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Liste\\\/\",\"view_label\":\"Liste\",\"aria_label\":\"Zeige Veranstaltungen in der Liste Ansicht\"},\"month\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Month_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Monat\\\/\",\"view_label\":\"Monat\",\"aria_label\":\"Zeige Veranstaltungen in der Monat Ansicht\"},\"day\":{\"view_class\":\"Tribe\\\\Events\\\\Views\\\\V2\\\\Views\\\\Day_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/heute\\\/\",\"view_label\":\"Tag\",\"aria_label\":\"Zeige Veranstaltungen in der Tag Ansicht\"},\"week\":{\"view_class\":\"Tribe\\\\Events\\\\Pro\\\\Views\\\\V2\\\\Views\\\\Week_View\",\"view_url\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/Woche\\\/\",\"view_label\":\"Woche\",\"aria_label\":\"Zeige Veranstaltungen in der Woche Ansicht\"}},\"show_latest_past\":false,\"past\":false,\"compatibility_classes\":[\"tribe-compatibility-container\"],\"view_more_text\":\"Kalender anzeigen\",\"view_more_title\":\"Weitere Veranstaltungen anzeigen.\",\"view_more_link\":\"https:\\\/\\\/welovekiel.com\\\/de\\\/Veranstaltungen\\\/\",\"widget_title\":\"Anstehende Veranstaltungen\",\"hide_if_no_upcoming_events\":false,\"display\":{\"cost\":false,\"venue\":false,\"street\":false,\"city\":false,\"region\":false,\"zip\":false,\"country\":false,\"phone\":false,\"organizer\":false,\"website\":false},\"subscribe_links\":{\"gcal\":{\"label\":\"Google Kalender\",\"single_label\":\"Zu Google Kalender hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasGoogleCalendar\"},\"ical\":{\"label\":\"iCalendar\",\"single_label\":\"Zu iCalendar hinzuf\\u00fcgen\",\"visible\":true,\"block_slug\":\"hasiCal\"},\"outlook-365\":{\"label\":\"Outlook 365\",\"single_label\":\"Outlook 365\",\"visible\":true,\"block_slug\":\"hasOutlook365\"},\"outlook-live\":{\"label\":\"Outlook Live\",\"single_label\":\"Outlook Live\",\"visible\":true,\"block_slug\":\"hasOutlookLive\"},\"ics\":{\"label\":\".ics-Datei exportieren\",\"single_label\":\".ics-Datei exportieren\",\"visible\":true,\"block_slug\":null},\"outlook-ics\":{\"label\":\"Exportiere Outlook .ics Datei\",\"single_label\":\"Exportiere Outlook .ics Datei\",\"visible\":true,\"block_slug\":null}},\"display_recurring_toggle\":false,\"_context\":{\"slug\":\"widget-events-list\"}}<\/script>\n\n\t\t\t\t\t\t\t<header class=\"tribe-events-widget-events-list__header\">\n\t\t\t\t\t<h2 class=\"tribe-events-widget-events-list__header-title tribe-common-h6 tribe-common-h--alt\">\n\t\t\t\t\t\tAnstehende Veranstaltungen\t\t\t\t\t<\/h2>\n\t\t\t\t<\/header>\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"tribe-events-widget-events-list__events\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-14\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t14\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000655 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-flohmarkt tag-flohmarkt-kaufland tag-flohmarkt-kaufland-raisdorf tag-flohmarkt-kaufland-schwentinental tag-flohmarkt-kiel tag-flohmarkt-raisdorf tag-flohmarkt-schwentinental tag-kaufland tag-kaufland-flohmarkt tag-kaufland-raisdorf tag-kaufland-schwentinental tag-kiel tag-mergenthalerstrasse tag-raisdorf tag-schwentinental tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-kieler-umland tribe_events_cat-meimersdorf tribe_events_cat-shopping gallery-content-unit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-14\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-kaufland-schwentinental-raisdorf-14-5-2026\/\" title=\"Flohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Kaufland Schwentinental \/ Raisdorf 14.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000638 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-famila tag-famila-wik tag-flohmarkt tag-flohmarkt-famila tag-flohmarkt-famila-wik tag-flohmarkt-kiel tag-kiel tag-prinz-heinrich-strasse tag-shopping tag-wik tribe_events_cat-flohmarkt tribe_events_cat-kiel tribe_events_cat-shopping tribe_events_cat-wik gallery-content-unit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-event-date-start\">06:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-famila-kiel-wik-17-5-2026\/\" title=\"Flohmarkt famila Kiel-Wik 17.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt famila Kiel-Wik 17.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tribe-common-g-row tribe-events-widget-events-list__event-row\">\n\n\t<div class=\"tribe-events-widget-events-list__event-date-tag tribe-common-g-col\">\n\t<time class=\"tribe-events-widget-events-list__event-date-tag-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-month\">\n\t\t\tMai\t\t<\/span>\n\t\t<span class=\"tribe-events-widget-events-list__event-date-tag-daynum tribe-common-h2 tribe-common-h4--min-medium\">\n\t\t\t17\t\t<\/span>\n\t<\/time>\n<\/div>\n\n\t<div class=\"tribe-events-widget-events-list__event-wrapper tribe-common-g-col\">\n\t\t<article class=\"tribe-events-widget-events-list__event post-10000646 tribe_events type-tribe_events status-publish has-post-thumbnail hentry tag-3262 tag-citti-park tag-citti-park-flohmarkt tag-citti-park-kiel tag-flohmarkt tag-flohmarkt-kiel tag-hassee tag-shopping tribe_events_cat-flohmarkt tribe_events_cat-hassee tribe_events_cat-kiel tribe_events_cat-shopping gallery-content-unit\">\n\t\t\t<div class=\"tribe-events-widget-events-list__event-details\">\n\n\t\t\t\t<header class=\"tribe-events-widget-events-list__event-header\">\n\t\t\t\t\t<div class=\"tribe-events-widget-events-list__event-datetime-wrapper tribe-common-b2 tribe-common-b3--min-medium\">\n\t\t<time class=\"tribe-events-widget-events-list__event-datetime\" datetime=\"2026-05-17\">\n\t\t<span class=\"tribe-event-date-start\">08:00<\/span> - <span class=\"tribe-event-time\">16:00<\/span>\t<\/time>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"tribe-events-widget-events-list__event-title tribe-common-h7\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/event\/flohmarkt-citti-park-kiel-17-5-2026\/\" title=\"Flohmarkt Citti-Park Kiel 17.5.2026\" rel=\"bookmark\" class=\"tribe-events-widget-events-list__event-title-link tribe-common-anchor-thin\">\n\t\tFlohmarkt Citti-Park Kiel 17.5.2026\t<\/a>\n<\/h3>\n\t\t\t\t<\/header>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/article>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tribe-events-widget-events-list__view-more tribe-common-b1 tribe-common-b2--min-medium\">\n\t<a href=\"https:\/\/welovekiel.com\/de\/Veranstaltungen\/\" class=\"tribe-events-widget-events-list__view-more-link tribe-common-anchor-thin\" title=\"Weitere Veranstaltungen anzeigen.\">\n\t\tKalender anzeigen\t<\/a>\n<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<script data-js=\"tribe-events-view-nonce-data\" type=\"application\/json\">{\"tvn1\":\"4a748144a2\",\"tvn2\":\"\"}<\/script><div class=\"fusion-additional-widget-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":15643,"template":"","gallery-category":[502,277,533,339],"gallery-tag":[750,950,278,499,3064,1039,3063],"gallery-event":[957,3065],"gallery-place":[485,279,505],"gallery-date":[2663],"gallery-person":[],"gallery-photographer":[291],"class_list":["post-15684","gallery","type-gallery","status-publish","has-post-thumbnail","hentry","gallery-category-duesternbrook","gallery-category-kieler-foerde","gallery-category-kieler-hafen","gallery-category-veranstaltungen-events","gallery-tag-duesternbrook","gallery-tag-feuerwerk","gallery-tag-kieler-foerde","gallery-tag-kiellinie","gallery-tag-neujahr","gallery-tag-reventlouwiese","gallery-tag-silvester","gallery-event-feuerwerk","gallery-event-silvester","gallery-place-duesternbrook","gallery-place-kieler-foerde","gallery-place-kiellinie","gallery-date-2663","gallery-photographer-christian-gewiese","gallery-content-unit"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery\/15684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/types\/gallery"}],"author":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery\/15684\/revisions"}],"predecessor-version":[{"id":15685,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery\/15684\/revisions\/15685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media\/15643"}],"wp:attachment":[{"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/media?parent=15684"}],"wp:term":[{"taxonomy":"gallery-category","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-category?post=15684"},{"taxonomy":"gallery-tag","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-tag?post=15684"},{"taxonomy":"gallery-event","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-event?post=15684"},{"taxonomy":"gallery-place","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-place?post=15684"},{"taxonomy":"gallery-date","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-date?post=15684"},{"taxonomy":"gallery-person","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-person?post=15684"},{"taxonomy":"gallery-photographer","embeddable":true,"href":"https:\/\/welovekiel.com\/de\/wp-json\/wp\/v2\/gallery-photographer?post=15684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}